{"id":87753,"date":"2019-02-03T19:33:32","date_gmt":"2019-02-03T18:33:32","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/"},"modified":"2026-07-11T03:49:46","modified_gmt":"2026-07-11T01:49:46","slug":"kitesurf-volare-sulle-onde-aglioti-l-9788865941706","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/","title":{"rendered":"kitesurf. volare sulle onde"},"content":{"rendered":"<p>Questo libro &egrave; allo stesso tempo un manuale completo con tutte le nozioni necessarie su attrezzature, manovre, spot, sicurezza (fino alle diverse specialit&agrave; agonistiche e ai regolamenti di gara) e&nbsp;un racconto dell&#8217;esperienza personale dell&#8217;autrice che, dopo un brutto incidente, &egrave; tornata sulla tavola diventando una forte atleta e un&#8217;istruttrice internazionale, capace quindi di coniugare passione e informazioni tecniche, con le raccomandazioni indispensabili sulla sicurezza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>attrezzature, tecniche, manovre, spot e sicurezza<\/p>\n<p class=\"autore\"><span>Author: <\/span>aglioti l.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Nutrimenti<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788865941706<\/p>\n","protected":false},"featured_media":153398,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3079],"product_tag":[],"class_list":{"0":"post-87753","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kitesurf-sup-and-windsurf","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>kitesurf. volare sulle onde - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"kitesurf. volare sulle onde\" \/>\n<meta property=\"og:description\" content=\"Subtitle: attrezzature, tecniche, manovre, spot e sicurezzaAuthor: aglioti l.Publisher: NutrimentiISBN: 9788865941706\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T01:49:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/kitesurfvolaresulleonde-agliotinutrimenti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"415\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;16,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\\\/\",\"name\":\"kitesurf. volare sulle onde - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/kitesurfvolaresulleonde-agliotinutrimenti.jpg\",\"datePublished\":\"2019-02-03T18:33:32+00:00\",\"dateModified\":\"2026-07-11T01:49:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/kitesurfvolaresulleonde-agliotinutrimenti.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/kitesurfvolaresulleonde-agliotinutrimenti.jpg\",\"width\":415,\"height\":599},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"kitesurf. volare sulle onde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"16.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788865941706\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"kitesurf. volare sulle onde - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/","og_locale":"en_US","og_type":"article","og_title":"kitesurf. volare sulle onde","og_description":"Subtitle: attrezzature, tecniche, manovre, spot e sicurezzaAuthor: aglioti l.Publisher: NutrimentiISBN: 9788865941706","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T01:49:46+00:00","og_image":[{"width":415,"height":599,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/kitesurfvolaresulleonde-agliotinutrimenti.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;16,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/","name":"kitesurf. volare sulle onde - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/kitesurfvolaresulleonde-agliotinutrimenti.jpg","datePublished":"2019-02-03T18:33:32+00:00","dateModified":"2026-07-11T01:49:46+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/kitesurfvolaresulleonde-agliotinutrimenti.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/kitesurfvolaresulleonde-agliotinutrimenti.jpg","width":415,"height":599},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/kitesurf-volare-sulle-onde-aglioti-l-9788865941706\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"kitesurf. volare sulle onde"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"16.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788865941706","product_condition":"new"},"df_price":16,"df_sale_price":"","df_regular_price":16,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/kitesurfvolaresulleonde-agliotinutrimenti-208x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/87753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=87753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/153398"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=87753"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=87753"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=87753"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=87753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}