{"id":87671,"date":"2019-02-03T19:34:00","date_gmt":"2019-02-03T18:34:00","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/"},"modified":"2026-07-11T03:48:20","modified_gmt":"2026-07-11T01:48:20","slug":"carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/","title":{"rendered":"carlo la leggenda, riva il mito volume I"},"content":{"rendered":"<p>Contenuto del libro: 1822-1906 La nascita del Cantiere; 1907-1939 Serafino, la tecnica e le corse; 1940-1949 Serafino, il giro di boa; 1950-1959 Dal sogno americano al miracolo italiano; la costruzione del mito; 1960-1969 All&#8217;apice del successo Carlo vende; 1970-1995 La vetroresina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>la storia<\/p>\n<p class=\"autore\"><span>Author: <\/span>gibellini p.m.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Edizioni Piem<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788897800002<\/p>\n","protected":false},"featured_media":127497,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3007,2739],"product_tag":[],"class_list":{"0":"post-87671","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-monographs","7":"product_cat-motorboating","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>carlo la leggenda, riva il mito volume I - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"carlo la leggenda, riva il mito volume I\" \/>\n<meta property=\"og:description\" content=\"Subtitle: la storiaAuthor: gibellini p.m.Publisher: Edizioni PiemISBN: 9788897800002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T01:48:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carloleggenda1-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"453\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;65,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\\\/\",\"name\":\"carlo la leggenda, riva il mito volume I - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/carloleggenda1-6.jpg\",\"datePublished\":\"2019-02-03T18:34:00+00:00\",\"dateModified\":\"2026-07-11T01:48:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/carloleggenda1-6.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/carloleggenda1-6.jpg\",\"width\":453,\"height\":598},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"carlo la leggenda, riva il mito volume I\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"65.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788897800002\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"carlo la leggenda, riva il mito volume I - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/","og_locale":"en_US","og_type":"article","og_title":"carlo la leggenda, riva il mito volume I","og_description":"Subtitle: la storiaAuthor: gibellini p.m.Publisher: Edizioni PiemISBN: 9788897800002","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T01:48:20+00:00","og_image":[{"width":453,"height":598,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carloleggenda1-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;65,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/","name":"carlo la leggenda, riva il mito volume I - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carloleggenda1-6.jpg","datePublished":"2019-02-03T18:34:00+00:00","dateModified":"2026-07-11T01:48:20+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carloleggenda1-6.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carloleggenda1-6.jpg","width":453,"height":598},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/carlo-la-leggenda-riva-il-mito-volume-i-gibellini-p-m-9788897800002\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"carlo la leggenda, riva il mito volume I"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"65.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788897800002","product_condition":"new"},"df_price":65,"df_sale_price":"","df_regular_price":65,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/carloleggenda1-6-227x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/87671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=87671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/127497"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=87671"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=87671"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=87671"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=87671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}