{"id":87071,"date":"2019-02-03T19:18:18","date_gmt":"2019-02-03T18:18:18","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/"},"modified":"2026-07-11T04:37:19","modified_gmt":"2026-07-11T02:37:19","slug":"appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/","title":{"rendered":"appunti sparsi su una gita di piacere"},"content":{"rendered":"<p>&#8220;Appunti sparsi su una gita di piacere&#8221; di Mark Twain&nbsp;&egrave; il resoconto divertentissimo di un &#8220;viaggio immaginario&#8221;, anche se questa volta pi&ugrave; concreto: in battello, da New York a New Haven e alle Bermuda; un viaggio &#8220;di piacere&#8221;&nbsp;(turistico, si direbbe oggi) dove, fra incontri, conversazioni e&nbsp;descrizioni, assistiamo al dispiegarsi dell&#8217;incontenibile genio umoristico del grande scrittore americano. Completano il nostro volume altri due brevi, spassosissimi racconti: &#8220;La grande rivoluzione di Pitcairn&#8221; e la &#8220;Dissertazione sui neonati&#8221;.<\/p>\n<p>Edizione: 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>twain m.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Passigli Editori<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788836816125<\/p>\n","protected":false},"featured_media":125419,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2965,2811],"product_tag":[],"class_list":{"0":"post-87071","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-short-stories-novels-and-articles","7":"product_cat-short-stories","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>appunti sparsi su una gita di piacere - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"appunti sparsi su una gita di piacere\" \/>\n<meta property=\"og:description\" content=\"Author: twain m.Publisher: Passigli EditoriISBN: 9788836816125\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T02:37:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appuntisparsisuunagitadipiacere-twain-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"316\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;9,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\\\/\",\"name\":\"appunti sparsi su una gita di piacere - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/appuntisparsisuunagitadipiacere-twain-2.jpg\",\"datePublished\":\"2019-02-03T18:18:18+00:00\",\"dateModified\":\"2026-07-11T02:37:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/appuntisparsisuunagitadipiacere-twain-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/appuntisparsisuunagitadipiacere-twain-2.jpg\",\"width\":316,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"appunti sparsi su una gita di piacere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"9.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788836816125\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"appunti sparsi su una gita di piacere - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/","og_locale":"en_US","og_type":"article","og_title":"appunti sparsi su una gita di piacere","og_description":"Author: twain m.Publisher: Passigli EditoriISBN: 9788836816125","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T02:37:19+00:00","og_image":[{"width":316,"height":520,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appuntisparsisuunagitadipiacere-twain-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;9,50","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/","name":"appunti sparsi su una gita di piacere - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appuntisparsisuunagitadipiacere-twain-2.jpg","datePublished":"2019-02-03T18:18:18+00:00","dateModified":"2026-07-11T02:37:19+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appuntisparsisuunagitadipiacere-twain-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appuntisparsisuunagitadipiacere-twain-2.jpg","width":316,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/appunti-sparsi-su-una-gita-di-piacere-twain-m-9788836816125\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"appunti sparsi su una gita di piacere"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"9.50","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788836816125","product_condition":"new"},"df_price":9.5,"df_sale_price":"","df_regular_price":9.5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/appuntisparsisuunagitadipiacere-twain-2-182x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/87071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=87071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/125419"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=87071"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=87071"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=87071"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=87071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}