{"id":87031,"date":"2019-02-03T19:18:30","date_gmt":"2019-02-03T18:18:30","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/"},"modified":"2026-07-11T04:36:36","modified_gmt":"2026-07-11T02:36:36","slug":"i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/","title":{"rendered":"i migliori surfer del mondo"},"content":{"rendered":"<p>Questo volume si rivolge a tutti gli appassionati del surf a vela, siano essi principianti oppure emuli dei dodici protagonisti intervistati. Questi (da Robby Nash a J&uuml;rgen H&ouml;nscheid, da Suzan Gedayloo a Mike Waltze, da Peter Cabrinha a Stephan van den Berg) raccontano come sono arrivati al surf a vela, come questo sport &egrave; diventato parte integrante della loro vita e come hanno raggiunto il successo. Ogni surfer parla di s&eacute;, descrive le proprie esperienze nei vari settori e nelle diverse specialit&agrave;: dalla progettazione delle tavole ai tagli delle vele, dai segreti per una buona navigazione alla tattica di gara. Ognuno di loro rivela i suoi progetti per il futuro e come saranno domani tavole e attrezzature, trasmette al lettore con semplicit&agrave; le sue emozioni, le sue paure quando affronta il mare in condizioni estreme. Inoltre essi insegnano in modo chiaro ed efficace le loro tecniche per i salti e per le manovre pi&ugrave; difficili. Il testo, semplice e di lettura gradevole, &egrave; corredato da splendide fotografie che ritraggono i dodici surfer nelle loro esibizioni pi&ugrave; belle e&nbsp;nelle acrobazie pi&ugrave; spettacolari.<\/p>\n<p>Edizione: 1984<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>seer u.  stanciu u.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788842587309<\/p>\n","protected":false},"featured_media":133724,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3079],"product_tag":[],"class_list":{"0":"post-87031","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kitesurf-sup-and-windsurf","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>i migliori surfer del mondo - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"i migliori surfer del mondo\" \/>\n<meta property=\"og:description\" content=\"Author: seer u. stanciu u.Publisher: Ugo Mursia EditoreISBN: 9788842587309\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T02:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/migliorisurferdelmondo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;24,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\\\/\",\"name\":\"i migliori surfer del mondo - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/migliorisurferdelmondo-1.jpg\",\"datePublished\":\"2019-02-03T18:18:30+00:00\",\"dateModified\":\"2026-07-11T02:36:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/migliorisurferdelmondo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/migliorisurferdelmondo-1.jpg\",\"width\":400,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"i migliori surfer del mondo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"24.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788842587309\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"i migliori surfer del mondo - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/","og_locale":"en_US","og_type":"article","og_title":"i migliori surfer del mondo","og_description":"Author: seer u. stanciu u.Publisher: Ugo Mursia EditoreISBN: 9788842587309","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T02:36:36+00:00","og_image":[{"width":400,"height":531,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/migliorisurferdelmondo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;24,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/","name":"i migliori surfer del mondo - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/migliorisurferdelmondo-1.jpg","datePublished":"2019-02-03T18:18:30+00:00","dateModified":"2026-07-11T02:36:36+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/migliorisurferdelmondo-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/migliorisurferdelmondo-1.jpg","width":400,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-migliori-surfer-del-mondo-seer-u-stanciu-u-9788842587309\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"i migliori surfer del mondo"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"24.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788842587309","product_condition":"new"},"df_price":24,"df_sale_price":"","df_regular_price":24,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/migliorisurferdelmondo-1-226x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/87031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=87031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/133724"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=87031"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=87031"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=87031"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=87031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}