{"id":86343,"date":"2019-02-03T19:22:11","date_gmt":"2019-02-03T18:22:11","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/"},"modified":"2026-07-11T04:24:37","modified_gmt":"2026-07-11T02:24:37","slug":"superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/","title":{"rendered":"superyachts"},"content":{"rendered":"<p>La lunga tradizione della realt&agrave; ligure nell&rsquo;industria nautica italiana costituisce il naturale scenario in cui si inserisce l&rsquo;attivit&agrave; formativa dell&rsquo;Universit&agrave; di Genova, impegnata a creare figure in grado di interpretare e anticipare le tendenze di un settore indissolubilmente legato a doppio filo con i principi dell&rsquo;industrial design costantemente in cambiamento. L&rsquo;esperienza condotta dagli studenti del Laboratorio di Design Nautico 5, guidata da Massimo-Musio Sale, Mario Ivan Zignego e Maria Carola Morozzo della Rocca, ha riguardato diversi argomenti: dalla nuova progettazione al refitting di imbarcazioni di diversa tipologia e dimensioni, dal design degli interni delle navi al product design nell&rsquo;ambito degli accessori, sempre valutando l&rsquo;impatto delle scelte operate, soprattutto dal punto di vista della responsabilit&agrave; ambientale. La collaborazione tra figure di diverso background culturale (architetti, designer, ingegneri, professionisti) costituisce una grande ricchezza che metaforicamente ricorda l&rsquo;apertura e la mescolanza dei linguaggi caratteristica dei porti di mare. I diversi gruppi di lavoro hanno individuato il tema, concentrando la ricerca sul settore dei superyachts, sia a vela sia a motore, hanno svolto un&rsquo;indagine di mercato, selezionando i prodotti potenzialmente concorrenti e&nbsp;li hanno analizzati, determinando successivamente un elaborato conoscitivo dove sono chiaramente individuati i punti di forza e di debolezza di ciascuna imbarcazione, identificando, perci&ograve;, un modello tipologico archetipico. In seguito, per ogni imbarcazione &egrave; stata elaborata una proposta, dando motivazione di ogni variazione progettuale rispetto al modello di riferimento. La comparazione porta anche a valutare le diverse soluzioni tecniche e distributive adottate dalle barche di riferimento e a operare consapevolmente una selezione ragionata verso la proposta pi&ugrave; funzionale, nell&rsquo;ottica della soddisfazione dei requisiti e delle aspettative del progetto. Grande attenzione &egrave; stata posta all&rsquo;analisi dei percorsi che passeggeri ed equipaggio seguono durante la vita di bordo. &Egrave; interessante notare come, per sostenere la validit&agrave; e la pertinenza delle soluzioni proposte, spesso si assista alla presentazione di soluzioni progettuali provenienti da ambiti del tutto diversi dalla nautica da diporto: citazioni dal campo dell&rsquo;architettura, dell&rsquo;interior design, del car design e dell&rsquo;oggettistica, che innescano intriganti contaminazioni interdisciplinari che spesso portano a risultati di grande innovazione. Le 18 schede presentate nel libro relative a 18 progetti diversi, frutto del lavoro del Laboratorio di Design Nautico 5, testimoniano cos&igrave; come le barche oggi si costruiscano con una complessit&agrave; inedita rispetto al passato e si progettino con una perizia di dettagli, con una quantit&agrave; di particolari e con un&rsquo;infinit&agrave; di confort sconosciute alla tradizione nautica fino a trent&rsquo;anni fa.<\/p>\n<p>Lingue: Italiano e Inglese<\/p>\n<p>Edizione: 2010<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>yacht design studio workshop<\/p>\n<p class=\"autore\"><span>Author: <\/span>musio-sale m.  zignego m.i.  morozzo della rocca m<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>dogma srl<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788887434422<\/p>\n","protected":false},"featured_media":127731,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2788],"product_tag":[],"class_list":{"0":"post-86343","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tiger-shark","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>superyachts - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"superyachts\" \/>\n<meta property=\"og:description\" content=\"Subtitle: yacht design studio workshopAuthor: musio-sale m. zignego m.i. morozzo della rocca mPublisher: dogma srlISBN: 9788887434422\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T02:24:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/superyachts-yachtdesignstudioworkshopmusiosalezignegomorozzodellarocca-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"347\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;50,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\\\/\",\"name\":\"superyachts - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/superyachts-yachtdesignstudioworkshopmusiosalezignegomorozzodellarocca-2.jpg\",\"datePublished\":\"2019-02-03T18:22:11+00:00\",\"dateModified\":\"2026-07-11T02:24:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/superyachts-yachtdesignstudioworkshopmusiosalezignegomorozzodellarocca-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/superyachts-yachtdesignstudioworkshopmusiosalezignegomorozzodellarocca-2.jpg\",\"width\":300,\"height\":347},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"superyachts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"50.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788887434422\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"superyachts - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/","og_locale":"en_US","og_type":"article","og_title":"superyachts","og_description":"Subtitle: yacht design studio workshopAuthor: musio-sale m. zignego m.i. morozzo della rocca mPublisher: dogma srlISBN: 9788887434422","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T02:24:37+00:00","og_image":[{"width":300,"height":347,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/superyachts-yachtdesignstudioworkshopmusiosalezignegomorozzodellarocca-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;50,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/","name":"superyachts - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/superyachts-yachtdesignstudioworkshopmusiosalezignegomorozzodellarocca-2.jpg","datePublished":"2019-02-03T18:22:11+00:00","dateModified":"2026-07-11T02:24:37+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/superyachts-yachtdesignstudioworkshopmusiosalezignegomorozzodellarocca-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/superyachts-yachtdesignstudioworkshopmusiosalezignegomorozzodellarocca-2.jpg","width":300,"height":347},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/superyachts-musio-sale-m-zignego-m-i-morozzo-della-rocca-m-9788887434422\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"superyachts"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"50.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788887434422","product_condition":"new"},"df_price":50,"df_sale_price":"","df_regular_price":50,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/superyachts-yachtdesignstudioworkshopmusiosalezignegomorozzodellarocca-2-259x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/86343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=86343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/127731"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=86343"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=86343"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=86343"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=86343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}