{"id":85392,"date":"2019-02-03T19:12:28","date_gmt":"2019-02-03T18:12:28","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/"},"modified":"2026-07-11T04:50:52","modified_gmt":"2026-07-11T02:50:52","slug":"storia-della-marina-italiana-i-manfroni-c-9788866971481","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/","title":{"rendered":"storia della marina italiana I"},"content":{"rendered":"<p>Gi&agrave; a fine Ottocento Camillo Manfroni si era accorto di come il racconto e l&#8217;analisi delle vicende navali ricoprissero un ruolo cruciale per l&#8217;indagine storica. Campo poco esplorato, la storia navale era considerata indispensabile per rintracciare le cause della perdita del dominio italiano nel Mediterraneo e far s&igrave; che la flotta nazionale recuperasse l&#8217;antico prestigio. L&#8217;attento lavoro compiuto da Manfroni, solida base per gli studi successivi, ha offerto cos&igrave; una nuova prospettiva di osservazione per gli eventi che hanno visto protagonista la flotta italiana. Dalle invasioni barbariche al trattato di Ninfeo, dalla caduta di Costantinopoli alla battaglia di Lepanto, Manfroni ripercorre in modo appassionante oltre un millennio di scontri navali in una ricostruzione storica meticolosa e avvincente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>dalle invasioni barbariche al trattato di ninfeo<\/p>\n<p class=\"autore\"><span>Author: <\/span>manfroni c.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>res gestae<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788866971481<\/p>\n","protected":false},"featured_media":130778,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3028],"product_tag":[],"class_list":{"0":"post-85392","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-prehistory-and-ancient-history","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>storia della marina italiana I - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"storia della marina italiana I\" \/>\n<meta property=\"og:description\" content=\"Subtitle: dalle invasioni barbariche al trattato di ninfeoAuthor: manfroni c.Publisher: res gestaeISBN: 9788866971481\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T02:50:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadellamarinaitaliana1resgestae-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"409\" \/>\n\t<meta property=\"og:image:height\" content=\"605\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;32,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-della-marina-italiana-i-manfroni-c-9788866971481\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-della-marina-italiana-i-manfroni-c-9788866971481\\\/\",\"name\":\"storia della marina italiana I - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-della-marina-italiana-i-manfroni-c-9788866971481\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-della-marina-italiana-i-manfroni-c-9788866971481\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/storiadellamarinaitaliana1resgestae-3.jpg\",\"datePublished\":\"2019-02-03T18:12:28+00:00\",\"dateModified\":\"2026-07-11T02:50:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-della-marina-italiana-i-manfroni-c-9788866971481\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-della-marina-italiana-i-manfroni-c-9788866971481\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-della-marina-italiana-i-manfroni-c-9788866971481\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/storiadellamarinaitaliana1resgestae-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/storiadellamarinaitaliana1resgestae-3.jpg\",\"width\":409,\"height\":605},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-della-marina-italiana-i-manfroni-c-9788866971481\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"storia della marina italiana I\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"32.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788866971481\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"storia della marina italiana I - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/","og_locale":"en_US","og_type":"article","og_title":"storia della marina italiana I","og_description":"Subtitle: dalle invasioni barbariche al trattato di ninfeoAuthor: manfroni c.Publisher: res gestaeISBN: 9788866971481","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T02:50:52+00:00","og_image":[{"width":409,"height":605,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadellamarinaitaliana1resgestae-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;32,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/","name":"storia della marina italiana I - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadellamarinaitaliana1resgestae-3.jpg","datePublished":"2019-02-03T18:12:28+00:00","dateModified":"2026-07-11T02:50:52+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadellamarinaitaliana1resgestae-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadellamarinaitaliana1resgestae-3.jpg","width":409,"height":605},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-della-marina-italiana-i-manfroni-c-9788866971481\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"storia della marina italiana I"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"32.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788866971481","product_condition":"new"},"df_price":32,"df_sale_price":"","df_regular_price":32,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storiadellamarinaitaliana1resgestae-3-203x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/85392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=85392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/130778"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=85392"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=85392"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=85392"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=85392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}