{"id":85247,"date":"2019-02-03T19:13:12","date_gmt":"2019-02-03T18:13:12","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/"},"modified":"2026-05-09T03:11:35","modified_gmt":"2026-05-09T01:11:35","slug":"i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/","title":{"rendered":"i giorni della luna rossa"},"content":{"rendered":"<p>&#8220;I giorni della Luna Rossa&#8221; &egrave; un diario senza tempo intorno alla straordinaria impresa sportiva dell&#8217;ultima sfida italiana alla Coppa America. Un racconto appassionato, dai risvolti tecnici, psicologici, economici, manageriali e scaramantici. Uno spaccato dell&#8217;America&#8217;s Cup, il pi&ugrave; antico trofeo sportivo all&#8217;alba del terzo millennio: dalla genesi della sfida di Prada alla nascita di Luna Rossa; dalla scoperta di Auckland e degli altri sfidanti, attraverso i tratti dei personaggi chiave (Patrizio Bertelli, Francesco De Angelis, Paul Cayard) di un&#8217;avventura capace di conquistare gli italiani, fino all&#8217;entrata in scena di Black Magic e dell&#8217;analisi dei segreti dell&#8217;imbattibilit&agrave; di Team New Zeland.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>colivicchi f.  venanzangeli p.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788842527121<\/p>\n","protected":false},"featured_media":132847,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805],"product_tag":[],"class_list":{"0":"post-85247","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>i giorni della luna rossa - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"i giorni della luna rossa\" \/>\n<meta property=\"og:description\" content=\"Author: colivicchi f. venanzangeli p.Publisher: Ugo Mursia EditoreISBN: 9788842527121\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T01:11:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/giornidellalunarossa-mursia-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"396\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;13,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\\\/\",\"name\":\"i giorni della luna rossa - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/giornidellalunarossa-mursia-3.jpg\",\"datePublished\":\"2019-02-03T18:13:12+00:00\",\"dateModified\":\"2026-05-09T01:11:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/giornidellalunarossa-mursia-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/giornidellalunarossa-mursia-3.jpg\",\"width\":396,\"height\":595},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"i giorni della luna rossa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"13.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788842527121\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"i giorni della luna rossa - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/","og_locale":"en_US","og_type":"article","og_title":"i giorni della luna rossa","og_description":"Author: colivicchi f. venanzangeli p.Publisher: Ugo Mursia EditoreISBN: 9788842527121","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T01:11:35+00:00","og_image":[{"width":396,"height":595,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/giornidellalunarossa-mursia-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;13,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/","name":"i giorni della luna rossa - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/giornidellalunarossa-mursia-3.jpg","datePublished":"2019-02-03T18:13:12+00:00","dateModified":"2026-05-09T01:11:35+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/giornidellalunarossa-mursia-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/giornidellalunarossa-mursia-3.jpg","width":396,"height":595},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/i-giorni-della-luna-rossa-colivicchi-f-venanzangeli-p-9788842527121\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"i giorni della luna rossa"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"13.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788842527121","product_condition":"new"},"df_price":13,"df_sale_price":"","df_regular_price":13,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/giornidellalunarossa-mursia-3-200x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/85247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=85247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/132847"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=85247"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=85247"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=85247"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=85247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}