{"id":85207,"date":"2019-02-03T19:13:38","date_gmt":"2019-02-03T18:13:38","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/mischief-in-patagonia-tilman-h-w-9788897173908\/"},"modified":"2026-05-09T03:11:07","modified_gmt":"2026-05-09T01:11:07","slug":"mischief-in-patagonia-tilman-h-w-9788897173908","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/","title":{"rendered":"mischief in patagonia"},"content":{"rendered":"<p>Negli anni successivi alla guerra, Tilman fece lunghe campagne d&#8217;esplorazione negli angoli pi&ugrave; remoti dell&#8217;Asia. Pakistan, Xinjihang, Kirghizistan, Tibet, Karakorum e Nepal.&nbsp; Poi si imbarc&ograve; sul &#8220;Mischief&#8221;, una barca-pilota in servizio al porto di Bristol dal 1906 e&nbsp;part&igrave; dall&#8217;Inghilterra meridionale per giungere in Patagonia dopo aver fatto scalo alle Canarie e in Uruguay. Da Punta Arenas Tilman percorse lo Stretto di Magellano e si introdusse nell&#8217;Estero Peel. Qui comp&igrave; la prima traversata nei due sensi della sterminata Calotta Glaciale Patagonica e&nbsp;torn&ograve; in Inghilterra via Panama, dopo aver percorso circa 20000 miglia in mare. Da quel momento in poi Tilman organizz&ograve; una spedizione ogni 1-2 anni, portando Mischief in Antartide, intorno all&#8217;Africa, alle isole Kerguelen, alle Spitzbergen, in Groenlandia oltre sei volte e&nbsp;sull&#8217;isola di Baffin. In Groenlandia perse &#8220;Mischief&#8221;, che sostitu&igrave; prima con &#8220;Sea Breeze&#8221; e&nbsp;poi con &#8220;Baroque&#8221;, entrambe gemelle della prima. Nel 1977, a quasi 80 anni, fu invitato a capitanare una grossa barca per una spedizione in Antartide: accett&ograve;, ma durante la seconda tappa della traversata, tra Rio de Janeiro e Stanley, nelle isole Falkland, la nave scomparve il 1&ordm; novembre 1977. Secondo il Royal Geographical Society venne dichiarato morto nel 1979.<\/p>\n<p>Edizione: 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>tilman h.w.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Edizioni Mare Verticale (Gruppo Santelli)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788897173908<\/p>\n","protected":false},"featured_media":125555,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805,2961],"product_tag":[],"class_list":{"0":"post-85207","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","7":"product_cat-chronicles-logbooks-and-travel-reports","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>mischief in patagonia - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"mischief in patagonia\" \/>\n<meta property=\"og:description\" content=\"Author: tilman h.w.Publisher: Edizioni Mare Verticale (Gruppo Santelli)ISBN: 9788897173908\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T01:11:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/mischiefinpatagonia-tilmanmareverticale-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"422\" \/>\n\t<meta property=\"og:image:height\" content=\"602\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;18,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/mischief-in-patagonia-tilman-h-w-9788897173908\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/mischief-in-patagonia-tilman-h-w-9788897173908\\\/\",\"name\":\"mischief in patagonia - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/mischief-in-patagonia-tilman-h-w-9788897173908\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/mischief-in-patagonia-tilman-h-w-9788897173908\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/mischiefinpatagonia-tilmanmareverticale-2.jpg\",\"datePublished\":\"2019-02-03T18:13:38+00:00\",\"dateModified\":\"2026-05-09T01:11:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/mischief-in-patagonia-tilman-h-w-9788897173908\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/mischief-in-patagonia-tilman-h-w-9788897173908\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/mischief-in-patagonia-tilman-h-w-9788897173908\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/mischiefinpatagonia-tilmanmareverticale-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/mischiefinpatagonia-tilmanmareverticale-2.jpg\",\"width\":422,\"height\":602},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/mischief-in-patagonia-tilman-h-w-9788897173908\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"mischief in patagonia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"18.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788897173908\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"mischief in patagonia - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/","og_locale":"en_US","og_type":"article","og_title":"mischief in patagonia","og_description":"Author: tilman h.w.Publisher: Edizioni Mare Verticale (Gruppo Santelli)ISBN: 9788897173908","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T01:11:07+00:00","og_image":[{"width":422,"height":602,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/mischiefinpatagonia-tilmanmareverticale-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;18,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/","name":"mischief in patagonia - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/mischiefinpatagonia-tilmanmareverticale-2.jpg","datePublished":"2019-02-03T18:13:38+00:00","dateModified":"2026-05-09T01:11:07+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/mischiefinpatagonia-tilmanmareverticale-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/mischiefinpatagonia-tilmanmareverticale-2.jpg","width":422,"height":602},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/mischief-in-patagonia-tilman-h-w-9788897173908\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"mischief in patagonia"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"18.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788897173908","product_condition":"new"},"df_price":18,"df_sale_price":"","df_regular_price":18,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/mischiefinpatagonia-tilmanmareverticale-2-210x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/85207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=85207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/125555"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=85207"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=85207"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=85207"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=85207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}