{"id":85073,"date":"2019-02-03T19:15:21","date_gmt":"2019-02-03T18:15:21","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/"},"modified":"2026-07-11T04:45:14","modified_gmt":"2026-07-11T02:45:14","slug":"navi-al-fronte-grienti-v-merlini-l-9788862614795","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/","title":{"rendered":"navi al fronte"},"content":{"rendered":"<p>Le date, i nomi, gli avvenimenti pi&ugrave; importanti e i fatti poco conosciuti della storia della Regia Marina durante la Prima Guerra Mondiale. Dal 24 Maggio 1915 e per 41 mesi di conflitto la Marina Italiana ebbe un ruolo da protagonista, a dimostrazione che la Grande Guerra non si combatt&eacute; solo nelle trincee e sulle montagne. La Marina adott&ograve; una strategia di attesa e di deterrenza basata sulla conquista del potere marittimo in Adriatico, di cui lo sbarramento del Canale d&rsquo;Otranto fu il pi&ugrave; fulgido esempio. Grazie all&rsquo;Ammiraglio Paolo Thaon di Revel, la Marina appront&ograve; le misure necessarie per difendere il patrimonio culturale e artistico italiano a partire da Venezia. A questo si aggiunsero vere e proprie operazioni che oggi definiremmo di carattere umanitario, quale il salvataggio del popolo e dell&rsquo;esercito serbo o&nbsp;la cessione di alcune navi per accogliere trovatelli, orfani, figli di pescatori morti in guerra o in mare a seguito di naufragio. Grazie al contributo della Marina nacquero le &#8220;navi-asilo&#8221; che a Genova, Bari, Napoli e Venezia arruolarono alla cultura del mare tanti &#8220;marinaretti&#8221; sottraendoli alla strada, alla fame e alla criminalit&agrave;. Non mancarono, infine, le eroiche e ardite operazioni, come la famigerata &#8220;Beffa di Buccari&#8221;, l&rsquo;impresa di Pola e la difficile operazione di Premuda, che la Marina Militare ancora oggi celebra ogni 10 Giugno come festa di Forza Armata, ad opera di Luigi Rizzo e Giuseppe Aonzo al comando dei MAS 15 e MAS 21.<\/p>\n<p>Edizione: 2015<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>la marina italiana e la grande guerra<\/p>\n<p class=\"autore\"><span>Author: <\/span>grienti v.  merlini l.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Mattioli 1885<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788862614795<\/p>\n","protected":false},"featured_media":131622,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3049],"product_tag":[],"class_list":{"0":"post-85073","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-from-1900-to-1918","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>navi al fronte - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"navi al fronte\" \/>\n<meta property=\"og:description\" content=\"Subtitle: la marina italiana e la grande guerraAuthor: grienti v. merlini l.Publisher: Mattioli 1885ISBN: 9788862614795\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T02:45:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navialfronte-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"417\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;15,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navi-al-fronte-grienti-v-merlini-l-9788862614795\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navi-al-fronte-grienti-v-merlini-l-9788862614795\\\/\",\"name\":\"navi al fronte - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navi-al-fronte-grienti-v-merlini-l-9788862614795\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navi-al-fronte-grienti-v-merlini-l-9788862614795\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/navialfronte-2.jpg\",\"datePublished\":\"2019-02-03T18:15:21+00:00\",\"dateModified\":\"2026-07-11T02:45:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navi-al-fronte-grienti-v-merlini-l-9788862614795\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navi-al-fronte-grienti-v-merlini-l-9788862614795\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navi-al-fronte-grienti-v-merlini-l-9788862614795\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/navialfronte-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/navialfronte-2.jpg\",\"width\":417,\"height\":598},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/navi-al-fronte-grienti-v-merlini-l-9788862614795\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"navi al fronte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"15.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788862614795\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"navi al fronte - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/","og_locale":"en_US","og_type":"article","og_title":"navi al fronte","og_description":"Subtitle: la marina italiana e la grande guerraAuthor: grienti v. merlini l.Publisher: Mattioli 1885ISBN: 9788862614795","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T02:45:14+00:00","og_image":[{"width":417,"height":598,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navialfronte-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;15,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/","name":"navi al fronte - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navialfronte-2.jpg","datePublished":"2019-02-03T18:15:21+00:00","dateModified":"2026-07-11T02:45:14+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navialfronte-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navialfronte-2.jpg","width":417,"height":598},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/navi-al-fronte-grienti-v-merlini-l-9788862614795\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"navi al fronte"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"15.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788862614795","product_condition":"new"},"df_price":15,"df_sale_price":"","df_regular_price":15,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/navialfronte-2-209x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/85073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=85073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/131622"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=85073"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=85073"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=85073"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=85073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}