{"id":84808,"date":"2019-02-03T19:06:45","date_gmt":"2019-02-03T18:06:45","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/luigi-rizzo-andriola-f-9788898485451\/"},"modified":"2026-07-11T05:09:32","modified_gmt":"2026-07-11T03:09:32","slug":"luigi-rizzo-andriola-f-9788898485451","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/","title":{"rendered":"luigi rizzo"},"content":{"rendered":"<p>Biografia di Luigi Rizzo, eroe della Marina, che con le sue imprese ha scritto pagine uniche nella storia della guerra sul mare.<\/p>\n<p>L&rsquo;autore Fabio Andriola ha esteso le indagini in numerosi archivi, ricostruendo un ritratto completo dell&rsquo;affondatore, dall&#8217;infanzia alle grandi imprese della Prima Guerra Mondiale, dalla vicenda di Fiume al complicato Dopoguerra italiano, dall&#8217;avvento del fascismo all&#8217;ascesa dei vertici di importanti complessi armatoriali nazionali, fino alla partecipazione al Secondo Conflitto Mondiale, all&#8217;attivit&agrave; politica, alla dura prigionia in Germania e al triste e faticoso rientro in Italia, seguito da un purtroppo rapido declino fisico. Ma, fino all&#8217;ultimo, Rizzo fu un &ldquo;uomo di mare&rdquo;: lo fu per nascita e vocazione, da civile e da militare.<\/p>\n<p>La ristampa di questo volume, presentato in una nuova veste editoriale, ha il significato profondo di omaggiare la figura di Luigi Rizzo affermando e consolidando i principi ispiratori della collana &ldquo;Uomini della Marina&rdquo; dell&rsquo;Ufficio Storico.<\/p>\n<p>Edizione: 2019<\/p>\n<p>Costo del libro &euro; 15,00 + &euro; 7,00 per la consegna in libreria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>andriola f.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ufficio Storico della Marina Militare<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788898485451 <\/p>\n","protected":false},"featured_media":131512,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,3055],"product_tag":[],"class_list":{"0":"post-84808","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-miscellaneous","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>luigi rizzo - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"luigi rizzo\" \/>\n<meta property=\"og:description\" content=\"Author: andriola f.Publisher: Ufficio Storico della Marina MilitareISBN: 9788898485451\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T03:09:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/luigi-rizzo-andriola-ufficio-storico-marina-2019-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"227\" \/>\n\t<meta property=\"og:image:height\" content=\"314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;23,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/luigi-rizzo-andriola-f-9788898485451\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/luigi-rizzo-andriola-f-9788898485451\\\/\",\"name\":\"luigi rizzo - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/luigi-rizzo-andriola-f-9788898485451\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/luigi-rizzo-andriola-f-9788898485451\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/luigi-rizzo-andriola-ufficio-storico-marina-2019-5.jpg\",\"datePublished\":\"2019-02-03T18:06:45+00:00\",\"dateModified\":\"2026-07-11T03:09:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/luigi-rizzo-andriola-f-9788898485451\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/luigi-rizzo-andriola-f-9788898485451\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/luigi-rizzo-andriola-f-9788898485451\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/luigi-rizzo-andriola-ufficio-storico-marina-2019-5.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/luigi-rizzo-andriola-ufficio-storico-marina-2019-5.jpg\",\"width\":227,\"height\":314},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/luigi-rizzo-andriola-f-9788898485451\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"luigi rizzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"23.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788898485451\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"luigi rizzo - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/","og_locale":"en_US","og_type":"article","og_title":"luigi rizzo","og_description":"Author: andriola f.Publisher: Ufficio Storico della Marina MilitareISBN: 9788898485451","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T03:09:32+00:00","og_image":[{"width":227,"height":314,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/luigi-rizzo-andriola-ufficio-storico-marina-2019-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;23,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/","name":"luigi rizzo - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/luigi-rizzo-andriola-ufficio-storico-marina-2019-5.jpg","datePublished":"2019-02-03T18:06:45+00:00","dateModified":"2026-07-11T03:09:32+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/luigi-rizzo-andriola-ufficio-storico-marina-2019-5.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/luigi-rizzo-andriola-ufficio-storico-marina-2019-5.jpg","width":227,"height":314},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/luigi-rizzo-andriola-f-9788898485451\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"luigi rizzo"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"23.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788898485451","product_condition":"new"},"df_price":23,"df_sale_price":"","df_regular_price":23,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/luigi-rizzo-andriola-ufficio-storico-marina-2019-5-217x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/84808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=84808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/131512"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=84808"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=84808"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=84808"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=84808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}