{"id":84602,"date":"2019-02-03T19:08:13","date_gmt":"2019-02-03T18:08:13","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/"},"modified":"2026-07-11T05:06:00","modified_gmt":"2026-07-11T03:06:00","slug":"le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/","title":{"rendered":"le convenzioni internazionali della navigazione marittima, interna e aerea"},"content":{"rendered":"<p>Il fenomeno legiferativo, anche nel campo della navigazione, ha manifestato, dal 1998 (epoca di pubblicazione della sesta edizione del Codice Annotato dell&#8217;Autore) ad oggi, un diffuso incremento degli interventi normativi sul piano internazionale, non solamente nel campo delle Convenzioni e degli Accordi tra gli Stati e dei relativi Protocolli di aggiornamento e modifica, ma, altres\u00ec, sul terreno di natura mista tecnico-giuridica oggetto di devoluzione delegata, da parte degli Stati, a comitati particolari creati ad hoc in seno ad Organizzazioni Mondiali di ampio respiro, quali nel nostro campo l&#8217;I.M.O., l&#8217;I.L.O. ecc., e anche a&nbsp;comitati impegnati in continue, frequenti elaborazioni normative che trascendono il campo dell&#8217;interesse privato per assurgere a strumenti impositivi generalizzati, e pertanto aventi natura ed effetti pubblici. Per altro verso, la Comunit\u00e0 europea si \u00e8 dedicata dal suo canto ad una continua elaborazione di Direttive e di Regolamenti fondamentali per regolare i vari aspetti e le molteplici estrinsecazioni del fenomeno navigatorio, ma soggetti, a loro volta, a frequenti e ripetute modifiche ufficiali. A tale sorgente comunitaria di precetti normativi non pu\u00f2 non corrispondere, necessariamente, una continua elaborazione, da parte dei singoli organi legiferativi competenti nel seno dei singoli Stati facenti parte della Comunit\u00e0 Europea, di determinati strumenti normativi (leggi, decreti, regolamenti) volti all&#8217;attuazione delle predette Direttive e\/o Regolamenti europei, nonch\u00e9 alla concretizzazione delle modifiche successive. Sul piano pratico-editoriale si \u00e8 pertanto resa necessaria una separazione tra la pubblicazione del Codice e connessi Regolamenti della navigazione annotati e la distinta massiccia pubblicazione in altri 2 volumi delle tante Convenzioni, Accordi, Protocolli internazionali tra gli Stati.<\/p>\n<p>Libro in due volumi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>righetti g.  rimaboschi m.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>giuffr\u00e8 francis lefebvre<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788814137862<\/p>\n","protected":false},"featured_media":84603,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2629],"product_tag":[],"class_list":{"0":"post-84602","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-law","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>le convenzioni internazionali della navigazione marittima, interna e aerea - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"le convenzioni internazionali della navigazione marittima, interna e aerea\" \/>\n<meta property=\"og:description\" content=\"Author: righetti g. rimaboschi m.Publisher: giuffr\u00e8 francis lefebvreISBN: 9788814137862\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T03:06:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/leconvenzioniinternazionalidellanavigazionemarittimainternaeaerea.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"334\" \/>\n\t<meta property=\"og:image:height\" content=\"496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;280,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\\\/\",\"name\":\"le convenzioni internazionali della navigazione marittima, interna e aerea - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/leconvenzioniinternazionalidellanavigazionemarittimainternaeaerea.jpg\",\"datePublished\":\"2019-02-03T18:08:13+00:00\",\"dateModified\":\"2026-07-11T03:06:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/leconvenzioniinternazionalidellanavigazionemarittimainternaeaerea.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/leconvenzioniinternazionalidellanavigazionemarittimainternaeaerea.jpg\",\"width\":334,\"height\":496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"le convenzioni internazionali della navigazione marittima, interna e aerea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"280.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788814137862\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"le convenzioni internazionali della navigazione marittima, interna e aerea - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/","og_locale":"en_US","og_type":"article","og_title":"le convenzioni internazionali della navigazione marittima, interna e aerea","og_description":"Author: righetti g. rimaboschi m.Publisher: giuffr\u00e8 francis lefebvreISBN: 9788814137862","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T03:06:00+00:00","og_image":[{"width":334,"height":496,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/leconvenzioniinternazionalidellanavigazionemarittimainternaeaerea.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;280,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/","name":"le convenzioni internazionali della navigazione marittima, interna e aerea - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/leconvenzioniinternazionalidellanavigazionemarittimainternaeaerea.jpg","datePublished":"2019-02-03T18:08:13+00:00","dateModified":"2026-07-11T03:06:00+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/leconvenzioniinternazionalidellanavigazionemarittimainternaeaerea.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/leconvenzioniinternazionalidellanavigazionemarittimainternaeaerea.jpg","width":334,"height":496},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-convenzioni-internazionali-della-navigazione-marittima-interna-e-aerea-righetti-g-rimaboschi-m-9788814137862\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"le convenzioni internazionali della navigazione marittima, interna e aerea"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"280.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788814137862","product_condition":"new"},"df_price":280,"df_sale_price":"","df_regular_price":280,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/leconvenzioniinternazionalidellanavigazionemarittimainternaeaerea-202x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/84602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=84602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/84603"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=84602"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=84602"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=84602"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=84602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}