{"id":83470,"date":"2023-05-13T16:14:36","date_gmt":"2023-05-13T14:14:36","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/oil-on-canvas-twirl-nina-albiniova-ldm1683987274\/"},"modified":"2026-05-09T00:45:55","modified_gmt":"2026-05-08T22:45:55","slug":"oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/","title":{"rendered":"oil on canvas &#8220;tidebreaker&#8221;"},"content":{"rendered":"<p>Nina Albiniova is specialized in&nbsp;<strong><em>oil painting<\/em><\/strong>; she especially paints&nbsp;<strong><em>seascapes<\/em><\/strong>.<\/p>\n<p>Her paintings are born from&nbsp;<strong>a photograph taken at the sea and then reworked<\/strong>&nbsp;in her studio.<\/p>\n<p>Size: <strong>50&#215;50<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>2024<\/p>\n<p class=\"autore\"><span>Author: <\/span>nina albiniova<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>ninka-art<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1683987274<\/p>\n","protected":false},"featured_media":149490,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2436],"product_tag":[],"class_list":{"0":"post-83470","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-paintings","7":"product_shipping_class-packaging","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>oil on canvas &quot;tidebreaker&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"oil on canvas &quot;tidebreaker&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 2024Author: nina albiniovaManufacturer: ninka-artISBN: LDM1683987274\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:45:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tidebreaker-nina-albiniova-50x50-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"701\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;800,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\\\/\",\"name\":\"oil on canvas \\\"tidebreaker\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tidebreaker-nina-albiniova-50x50-3.jpg\",\"datePublished\":\"2023-05-13T14:14:36+00:00\",\"dateModified\":\"2026-05-08T22:45:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tidebreaker-nina-albiniova-50x50-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/tidebreaker-nina-albiniova-50x50-3.jpg\",\"width\":701,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"oil on canvas &#8220;tidebreaker&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"800.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1683987274\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"oil on canvas \"tidebreaker\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/","og_locale":"en_US","og_type":"article","og_title":"oil on canvas \"tidebreaker\"","og_description":"Subtitle: 2024Author: nina albiniovaManufacturer: ninka-artISBN: LDM1683987274","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:45:55+00:00","og_image":[{"width":701,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tidebreaker-nina-albiniova-50x50-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;800,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/","name":"oil on canvas \"tidebreaker\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tidebreaker-nina-albiniova-50x50-3.jpg","datePublished":"2023-05-13T14:14:36+00:00","dateModified":"2026-05-08T22:45:55+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tidebreaker-nina-albiniova-50x50-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tidebreaker-nina-albiniova-50x50-3.jpg","width":701,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/oil-on-canvas-tidebreaker-nina-albiniova-ldm1683987274\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"oil on canvas &#8220;tidebreaker&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"800.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"LDM1683987274","product_condition":"new"},"df_price":800,"df_sale_price":"","df_regular_price":800,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/tidebreaker-nina-albiniova-50x50-3-300x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/83470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=83470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/149490"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=83470"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=83470"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=83470"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=83470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}