{"id":73849,"date":"2023-02-17T12:58:26","date_gmt":"2023-02-17T11:58:26","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/"},"modified":"2026-05-09T00:50:43","modified_gmt":"2026-05-08T22:50:43","slug":"watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/","title":{"rendered":"watercolor &#8220;paesaggio invernale con capo figari&#8221;"},"content":{"rendered":"<p>Sandro Feruglio, a well-deserving naval painter and officer, is a passionate sailor who studied at the Naval Academy of Livorno. For over thirty years he has been painting ship portraits of sailboats and military ships.<\/p>\n<p>Flat frame in walnut and glass.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>44&#215;34 cm<\/p>\n<p class=\"autore\"><span>Author: <\/span>sandro feruglio<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>alessandro feruglio<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1676635104<\/p>\n","protected":false},"featured_media":119633,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2436],"product_tag":[],"class_list":{"0":"post-73849","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-paintings","7":"product_shipping_class-packaging","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>watercolor &quot;paesaggio invernale con capo figari&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"watercolor &quot;paesaggio invernale con capo figari&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 44x34 cmAuthor: sandro feruglioManufacturer: alessandro feruglioISBN: LDM1676635104\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:50:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acquerello-paesaggio-invernale-con-capo-figari-feruglio-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"704\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;440,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\\\/\",\"name\":\"watercolor \\\"paesaggio invernale con capo figari\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/acquerello-paesaggio-invernale-con-capo-figari-feruglio-1.jpg\",\"datePublished\":\"2023-02-17T11:58:26+00:00\",\"dateModified\":\"2026-05-08T22:50:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/acquerello-paesaggio-invernale-con-capo-figari-feruglio-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/acquerello-paesaggio-invernale-con-capo-figari-feruglio-1.jpg\",\"width\":704,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"watercolor &#8220;paesaggio invernale con capo figari&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"440.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1676635104\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"watercolor \"paesaggio invernale con capo figari\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/","og_locale":"en_US","og_type":"article","og_title":"watercolor \"paesaggio invernale con capo figari\"","og_description":"Subtitle: 44x34 cmAuthor: sandro feruglioManufacturer: alessandro feruglioISBN: LDM1676635104","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:50:43+00:00","og_image":[{"width":704,"height":550,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acquerello-paesaggio-invernale-con-capo-figari-feruglio-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;440,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/","name":"watercolor \"paesaggio invernale con capo figari\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acquerello-paesaggio-invernale-con-capo-figari-feruglio-1.jpg","datePublished":"2023-02-17T11:58:26+00:00","dateModified":"2026-05-08T22:50:43+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acquerello-paesaggio-invernale-con-capo-figari-feruglio-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acquerello-paesaggio-invernale-con-capo-figari-feruglio-1.jpg","width":704,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/watercolor-paesaggio-invernale-con-capo-figari-sandro-feruglio-ldm1676635104\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"watercolor &#8220;paesaggio invernale con capo figari&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"440.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"LDM1676635104","product_condition":"new"},"df_price":440,"df_sale_price":"","df_regular_price":440,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/acquerello-paesaggio-invernale-con-capo-figari-feruglio-1-300x234.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/73849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=73849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/119633"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=73849"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=73849"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=73849"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=73849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}