{"id":66390,"date":"2022-09-22T15:31:53","date_gmt":"2022-09-22T13:31:53","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/set-of-two-plates-aquatic-creatures-pinocchio-riccardo-capuzzo-ldm1663853511\/"},"modified":"2026-07-11T01:24:32","modified_gmt":"2026-07-10T23:24:32","slug":"pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/","title":{"rendered":"pinocchio 2 plates set (whales collection)"},"content":{"rendered":"<p>This set takes you back to <strong>the epic scene where Pinocchio travels into the depths of the ocean to find the whale that swallowed his father Geppetto<\/strong>.<\/p>\n<p><em>&#8220;<strong>All illustrations are hand-made<\/strong>&nbsp;using a pencil and then refined with China ink. A&nbsp;<strong>high-resolution scan<\/strong>&nbsp;follows, to faithfully maintain the visual characteristics of the hand drawing&rdquo;. Riccardo Capuzzo<\/em><\/p>\n<p>This plates set is made of <strong>finest Chinese porcelain<\/strong>&nbsp;and&nbsp;<strong>decorated in Italy<\/strong>.<\/p>\n<p>Diameters: <strong>29 cm and 16 cm<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>riccardo capuzzo<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>aquatic creatures<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>4751038790093<\/p>\n","protected":false},"featured_media":144187,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2409,2446],"product_tag":[],"class_list":{"0":"post-66390","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-home-design-marine-decor","7":"product_cat-kitchen","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>pinocchio 2 plates set (whales collection) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pinocchio 2 plates set (whales collection)\" \/>\n<meta property=\"og:description\" content=\"Author: riccardo capuzzoManufacturer: aquatic creaturesISBN: 4751038790093\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:24:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/set-due-piatti-aquatic-creatures-pinocchio-riccardo-capuzzo-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"730\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;150,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\\\/\",\"name\":\"pinocchio 2 plates set (whales collection) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/set-due-piatti-aquatic-creatures-pinocchio-riccardo-capuzzo-9.jpg\",\"datePublished\":\"2022-09-22T13:31:53+00:00\",\"dateModified\":\"2026-07-10T23:24:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/set-due-piatti-aquatic-creatures-pinocchio-riccardo-capuzzo-9.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/set-due-piatti-aquatic-creatures-pinocchio-riccardo-capuzzo-9.jpg\",\"width\":550,\"height\":730},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"pinocchio 2 plates set (whales collection)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"150.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"4751038790093\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"pinocchio 2 plates set (whales collection) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/","og_locale":"en_US","og_type":"article","og_title":"pinocchio 2 plates set (whales collection)","og_description":"Author: riccardo capuzzoManufacturer: aquatic creaturesISBN: 4751038790093","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:24:32+00:00","og_image":[{"width":550,"height":730,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/set-due-piatti-aquatic-creatures-pinocchio-riccardo-capuzzo-9.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;150,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/","name":"pinocchio 2 plates set (whales collection) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/set-due-piatti-aquatic-creatures-pinocchio-riccardo-capuzzo-9.jpg","datePublished":"2022-09-22T13:31:53+00:00","dateModified":"2026-07-10T23:24:32+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/set-due-piatti-aquatic-creatures-pinocchio-riccardo-capuzzo-9.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/set-due-piatti-aquatic-creatures-pinocchio-riccardo-capuzzo-9.jpg","width":550,"height":730},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-2-plates-set-whales-collection-riccardo-capuzzo-4751038790093\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"pinocchio 2 plates set (whales collection)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"150.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"4751038790093","product_condition":"new"},"df_price":150,"df_sale_price":"","df_regular_price":150,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/set-due-piatti-aquatic-creatures-pinocchio-riccardo-capuzzo-9-226x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/66390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=66390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/144187"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=66390"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=66390"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=66390"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=66390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}