{"id":65041,"date":"2019-02-03T18:58:14","date_gmt":"2019-02-03T17:58:14","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/"},"modified":"2026-05-09T03:44:00","modified_gmt":"2026-05-09T01:44:00","slug":"le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/","title":{"rendered":"le petit atlas maritime &#8211; plan de granville"},"content":{"rendered":"<p>Riproduzione di una stampa antica tratta dal volume &#8220;Le petit atlas maritime&#8221; del 1764.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 44,8&#215;32,4<\/p>\n<p class=\"autore\"><span>Author: <\/span>bellin j.-n.<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>28427648853486<\/p>\n","protected":false},"featured_media":65042,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2424],"product_tag":[],"class_list":{"0":"post-65041","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-europe-and-mediterranean-sea","7":"product_shipping_class-packaging","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>le petit atlas maritime - plan de granville - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"le petit atlas maritime - plan de granville\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 44,8x32,4Author: bellin j.-n.ISBN: 28427648853486\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T01:44:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lepetitatlasmaritimeplandegranville-28427648853486.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"779\" \/>\n\t<meta property=\"og:image:height\" content=\"579\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;10,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\\\/\",\"name\":\"le petit atlas maritime - plan de granville - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/lepetitatlasmaritimeplandegranville-28427648853486.jpg\",\"datePublished\":\"2019-02-03T17:58:14+00:00\",\"dateModified\":\"2026-05-09T01:44:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/lepetitatlasmaritimeplandegranville-28427648853486.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/lepetitatlasmaritimeplandegranville-28427648853486.jpg\",\"width\":779,\"height\":579},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"le petit atlas maritime &#8211; plan de granville\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"10.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"28427648853486\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"le petit atlas maritime - plan de granville - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/","og_locale":"en_US","og_type":"article","og_title":"le petit atlas maritime - plan de granville","og_description":"Subtitle: cm 44,8x32,4Author: bellin j.-n.ISBN: 28427648853486","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T01:44:00+00:00","og_image":[{"width":779,"height":579,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lepetitatlasmaritimeplandegranville-28427648853486.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;10,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/","name":"le petit atlas maritime - plan de granville - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lepetitatlasmaritimeplandegranville-28427648853486.jpg","datePublished":"2019-02-03T17:58:14+00:00","dateModified":"2026-05-09T01:44:00+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lepetitatlasmaritimeplandegranville-28427648853486.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lepetitatlasmaritimeplandegranville-28427648853486.jpg","width":779,"height":579},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-petit-atlas-maritime-plan-de-granville-bellin-j-n-28427648853486\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"le petit atlas maritime &#8211; plan de granville"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"10.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"28427648853486","product_condition":"new"},"df_price":10,"df_sale_price":"","df_regular_price":10,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lepetitatlasmaritimeplandegranville-28427648853486-300x223.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/65041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=65041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/65042"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=65041"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=65041"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=65041"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=65041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}