{"id":64835,"date":"2019-02-03T18:58:47","date_gmt":"2019-02-03T17:58:47","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/"},"modified":"2026-05-09T03:42:09","modified_gmt":"2026-05-09T01:42:09","slug":"bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/","title":{"rendered":"bolle in pentola (fipsas)"},"content":{"rendered":"<p>Questo libro vuole essere una raccolta di tutto quello che occorre sapere per cucinare bene un pesce, un crostaceo o un mollusco. Non &egrave; e non vuole essere una raccolta di ricette, anche se qualcuna &egrave; presentata e descritta al solo scopo di fare esempi o dare idee su cui basare piatti da preparare. Non specifica certo con che sapori &egrave; meglio cucinare un particolare pesce; compaiono s&igrave; suggerimenti, ma scopo principale &egrave; la descrizione di come pulire, a che temperatura esporre e quanto tempo occorre per ottenere un buon risultato. L&rsquo;aggiunta degli altri ingredienti &egrave; lasciata al cuoco. La fantasia deve regnare in cucina. Si prenda spunto dalle ricette indicate, ma il consiglio &egrave; quello di variarle con la propria fantasia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>manuale per la scelta, la conservazione, la preparazione e il consumo di tutti o quasi gli organismi marini commestibili<\/p>\n<p class=\"autore\"><span>Author: <\/span>paterlini f.  bocchi m. (a cura di)<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>editrice la mandragora<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788875861520<\/p>\n","protected":false},"featured_media":80740,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2601],"product_tag":[],"class_list":{"0":"post-64835","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-seafood-cuising","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>bolle in pentola (fipsas) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"bolle in pentola (fipsas)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: manuale per la scelta, la conservazione, la preparazione e il consumo di tutti o quasi gli organismi marini commestibiliAuthor: paterlini f. bocchi m. (a cura di)Publisher: editrice la mandragoraISBN: 9788875861520\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T01:42:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bolleinpentola3-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"624\" \/>\n\t<meta property=\"og:image:height\" content=\"609\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;16,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\\\/\",\"name\":\"bolle in pentola (fipsas) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/bolleinpentola3-1.jpg\",\"datePublished\":\"2019-02-03T17:58:47+00:00\",\"dateModified\":\"2026-05-09T01:42:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/bolleinpentola3-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/bolleinpentola3-1.jpg\",\"width\":624,\"height\":609},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"bolle in pentola (fipsas)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"16.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788875861520\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"bolle in pentola (fipsas) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/","og_locale":"en_US","og_type":"article","og_title":"bolle in pentola (fipsas)","og_description":"Subtitle: manuale per la scelta, la conservazione, la preparazione e il consumo di tutti o quasi gli organismi marini commestibiliAuthor: paterlini f. bocchi m. (a cura di)Publisher: editrice la mandragoraISBN: 9788875861520","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T01:42:09+00:00","og_image":[{"width":624,"height":609,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bolleinpentola3-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;16,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/","name":"bolle in pentola (fipsas) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bolleinpentola3-1.jpg","datePublished":"2019-02-03T17:58:47+00:00","dateModified":"2026-05-09T01:42:09+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bolleinpentola3-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bolleinpentola3-1.jpg","width":624,"height":609},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/bolle-in-pentola-fipsas-paterlini-f-bocchi-m-a-cura-di-9788875861520\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"bolle in pentola (fipsas)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"16.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788875861520","product_condition":"new"},"df_price":16,"df_sale_price":"","df_regular_price":16,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/bolleinpentola3-1-300x293.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/64835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=64835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/80740"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=64835"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=64835"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=64835"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=64835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}