{"id":64792,"date":"2019-02-03T18:58:55","date_gmt":"2019-02-03T17:58:55","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/"},"modified":"2026-07-11T05:33:59","modified_gmt":"2026-07-11T03:33:59","slug":"il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/","title":{"rendered":"il respiro nell&#8217;apnea"},"content":{"rendered":"<p>Un manuale completamente illustrato sulle tecniche di respirazione che permettono di trovare la disposizione ideale per l&#8217;apnea. Attraverso la pratica del pranayama (la scienza del respiro), si arriva, in modo del tutto naturale, a inspirare ed espirare la maggior quantit&agrave; d&#8217;aria con il minor sforzo e si rende pi&ugrave; favorevole l&#8217;apnea sia dal punto di vista muscolare sia da quello mentale, oltre a favorire movimenti elastici e fluidi, forza e resistenza fisica. Non si impara solo una tecnica, ma una nuova e sana abitudine che apporta enormi benefici nel quotidiano, oltre che nella pratica sportiva. Nato dalla collaborazione tra Umberto Pelizzari, recordman di apnea, Lisetta Landoni, insegnante di yoga e pranayama, e Anna Seddone, istruttrice di apnea di grande esperienza, questo testo individua, tra le tante, le tecniche di pranayama che meglio si confanno alle peculiarit&agrave; dell&#8217;apnea, adattandole alle esigenze di quest&#8217;ultima, perch&eacute;&nbsp;l&#8217;ingresso in acqua si trasformi prima di tutto in un&#8217;esperienza della mente e dei sensi. Un libro rivolto all&#8217;apneista neofita, al praticante esperto, all&#8217;istruttore di apnea e a tutti coloro che vogliono imparare a respirare.<\/p>\n<p>Edizione: 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>pelizzari u.  landoni l.  seddone a.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Ugo Mursia Editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788842543510<\/p>\n","protected":false},"featured_media":117959,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2584,2558],"product_tag":[],"class_list":{"0":"post-64792","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-diving-apnea-and-snorkeling","7":"product_cat-dvds-and-cd-roms","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>il respiro nell&#039;apnea - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"il respiro nell&#039;apnea\" \/>\n<meta property=\"og:description\" content=\"Author: pelizzari u. landoni l. seddone a.Publisher: Ugo Mursia EditoreISBN: 9788842543510\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T03:33:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/respironellapnea3-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"434\" \/>\n\t<meta property=\"og:image:height\" content=\"604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;34,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\\\/\",\"name\":\"il respiro nell'apnea - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/respironellapnea3-2.jpg\",\"datePublished\":\"2019-02-03T17:58:55+00:00\",\"dateModified\":\"2026-07-11T03:33:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/respironellapnea3-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/respironellapnea3-2.jpg\",\"width\":434,\"height\":604},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"il respiro nell&#8217;apnea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"34.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788842543510\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"il respiro nell'apnea - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/","og_locale":"en_US","og_type":"article","og_title":"il respiro nell'apnea","og_description":"Author: pelizzari u. landoni l. seddone a.Publisher: Ugo Mursia EditoreISBN: 9788842543510","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T03:33:59+00:00","og_image":[{"width":434,"height":604,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/respironellapnea3-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;34,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/","name":"il respiro nell'apnea - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/respironellapnea3-2.jpg","datePublished":"2019-02-03T17:58:55+00:00","dateModified":"2026-07-11T03:33:59+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/respironellapnea3-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/respironellapnea3-2.jpg","width":434,"height":604},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-respiro-nell-apnea-pelizzari-u-landoni-l-seddone-a-9788842543510\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"il respiro nell&#8217;apnea"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"34.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788842543510","product_condition":"new"},"df_price":34,"df_sale_price":"","df_regular_price":34,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/respironellapnea3-2-216x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/64792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=64792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/117959"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=64792"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=64792"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=64792"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=64792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}