{"id":64724,"date":"2019-02-03T18:59:12","date_gmt":"2019-02-03T17:59:12","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/"},"modified":"2026-05-09T03:41:05","modified_gmt":"2026-05-09T01:41:05","slug":"pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/","title":{"rendered":"pagina di giornale &#8211; l&#8217;illustration, journal universel 21\u00b0 annee vol. LXI, n. 1045 (samedi 7 mars 1863)"},"content":{"rendered":"<p>Questa riproduzione di una stampa antica (originale tratto da &#8220;L&#8217;Illustration&#8221;) &egrave; stata impressa con il torchio a mano su carta&nbsp;antichizzata&nbsp;e acquarellata a mano da pittori esperti.<\/p>\n<p>Prodotto artigianale.<\/p>\n<p>Made in Italy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>cm 30&#215;42<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>la casa della stampa<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>70038291252931<\/p>\n","protected":false},"featured_media":123210,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2914],"product_tag":[],"class_list":{"0":"post-64724","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vertical","7":"product_shipping_class-packaging","9":"first","10":"instock","11":"sale","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>pagina di giornale - l&#039;illustration, journal universel 21\u00b0 annee vol. LXI, n. 1045 (samedi 7 mars 1863) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pagina di giornale - l&#039;illustration, journal universel 21\u00b0 annee vol. LXI, n. 1045 (samedi 7 mars 1863)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: cm 30x42Manufacturer: la casa della stampaISBN: 70038291252931\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T01:41:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/70038291252931-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"432\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;34,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\\\/\",\"name\":\"pagina di giornale - l'illustration, journal universel 21\u00b0 annee vol. LXI, n. 1045 (samedi 7 mars 1863) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/70038291252931-2.jpg\",\"datePublished\":\"2019-02-03T17:59:12+00:00\",\"dateModified\":\"2026-05-09T01:41:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/70038291252931-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/70038291252931-2.jpg\",\"width\":432,\"height\":592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"pagina di giornale &#8211; l&#8217;illustration, journal universel 21\u00b0 annee vol. LXI, n. 1045 (samedi 7 mars 1863)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"34.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"70038291252931\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"pagina di giornale - l'illustration, journal universel 21\u00b0 annee vol. LXI, n. 1045 (samedi 7 mars 1863) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/","og_locale":"en_US","og_type":"article","og_title":"pagina di giornale - l'illustration, journal universel 21\u00b0 annee vol. LXI, n. 1045 (samedi 7 mars 1863)","og_description":"Subtitle: cm 30x42Manufacturer: la casa della stampaISBN: 70038291252931","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T01:41:05+00:00","og_image":[{"width":432,"height":592,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/70038291252931-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;34,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/","name":"pagina di giornale - l'illustration, journal universel 21\u00b0 annee vol. LXI, n. 1045 (samedi 7 mars 1863) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/70038291252931-2.jpg","datePublished":"2019-02-03T17:59:12+00:00","dateModified":"2026-05-09T01:41:05+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/70038291252931-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/70038291252931-2.jpg","width":432,"height":592},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pagina-di-giornale-l-illustration-journal-universel-21-annee-vol-lxi-n-1045-samedi-7-mars-1863-70038291252931\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"pagina di giornale &#8211; l&#8217;illustration, journal universel 21\u00b0 annee vol. LXI, n. 1045 (samedi 7 mars 1863)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"34.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"70038291252931","product_condition":"new"},"df_price":34,"df_sale_price":34,"df_regular_price":40,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/70038291252931-2-219x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/64724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=64724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/123210"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=64724"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=64724"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=64724"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=64724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}