{"id":64001,"date":"2019-02-03T19:01:17","date_gmt":"2019-02-03T18:01:17","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/"},"modified":"2026-07-11T05:23:16","modified_gmt":"2026-07-11T03:23:16","slug":"lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/","title":{"rendered":"lineamenti di diritto della navigazione"},"content":{"rendered":"<p>Indice del volume:<\/p>\n<p>&#8211; Codice della Navigazione. Mare territoriale<br \/>&#8211; Amministrazione della navigazione<br \/>&#8211; Capitanerie di Porto. Guardia costiera<br \/>&#8211; Gente di mare. Contratto di lavoro<br \/>&#8211; La Nave<br \/>&#8211; Armatore e Societ&agrave; di armamento<br \/>&#8211; Il Comandante della nave ed il suo equipaggio<br \/>&#8211; Documenti di bordo. La Guardia<br \/>&#8211; Adempimenti all&rsquo;arrivo ed alla partenza<br \/>&#8211; Diritto Marittimo Internazionale<br \/>&#8211; Noleggio. Trasporto. Polizza di carico<br \/>&#8211; Le Avarie<br \/>&#8211; Le Assicurazioni marittime<br \/>&#8211; Privilegio. Ipoteca navale. Sequestro<br \/>&#8211; Urto. Assistenza. Salvataggio<br \/>&#8211; Pilotaggio. Rimorchio<br \/>&#8211; Relitti: Ritrovamento. Recupero<br \/>&#8211; Disposizioni processuali, penali, disciplinari<br \/>&#8211; Glossario<br \/>&#8211; Vocabolario: Italiano-Inglese-Italiano<\/p>\n<p>Edizione: 2002<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>nicoli l.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>quaderni marinari<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788890331732<\/p>\n","protected":false},"featured_media":151320,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2629],"product_tag":[],"class_list":{"0":"post-64001","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-law","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>lineamenti di diritto della navigazione - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"lineamenti di diritto della navigazione\" \/>\n<meta property=\"og:description\" content=\"Author: nicoli l.Publisher: quaderni marinariISBN: 9788890331732\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T03:23:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lineamentididirittodellanavigazione-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"285\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;23,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\\\/\",\"name\":\"lineamenti di diritto della navigazione - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/lineamentididirittodellanavigazione-4.jpg\",\"datePublished\":\"2019-02-03T18:01:17+00:00\",\"dateModified\":\"2026-07-11T03:23:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/lineamentididirittodellanavigazione-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/lineamentididirittodellanavigazione-4.jpg\",\"width\":285,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"lineamenti di diritto della navigazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"23.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788890331732\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"lineamenti di diritto della navigazione - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/","og_locale":"en_US","og_type":"article","og_title":"lineamenti di diritto della navigazione","og_description":"Author: nicoli l.Publisher: quaderni marinariISBN: 9788890331732","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T03:23:16+00:00","og_image":[{"width":285,"height":400,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lineamentididirittodellanavigazione-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;23,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/","name":"lineamenti di diritto della navigazione - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lineamentididirittodellanavigazione-4.jpg","datePublished":"2019-02-03T18:01:17+00:00","dateModified":"2026-07-11T03:23:16+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lineamentididirittodellanavigazione-4.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lineamentididirittodellanavigazione-4.jpg","width":285,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/lineamenti-di-diritto-della-navigazione-nicoli-l-9788890331732\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"lineamenti di diritto della navigazione"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"23.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788890331732","product_condition":"new"},"df_price":23,"df_sale_price":"","df_regular_price":23,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/lineamentididirittodellanavigazione-4-214x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/64001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=64001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/151320"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=64001"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=64001"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=64001"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=64001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}