{"id":63580,"date":"2019-02-03T19:03:28","date_gmt":"2019-02-03T18:03:28","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/diario-di-viaggio-vol-1-1996-1997-delfino-e-3780120005204\/"},"modified":"2026-05-09T03:30:50","modified_gmt":"2026-05-09T01:30:50","slug":"diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/","title":{"rendered":"diario di viaggio vol. 1 (1996-1997)"},"content":{"rendered":"<p>Manoscritto a stampa corredato da preziosi schizzi in bianco e nero eseguiti da Emilio Delfino, navigatore curioso e illustre cartografo, nel corso delle Sue peregrinazioni. Il presente volume raffigura e descrive le seguenti destinazioni: San Pietroburgo, Egitto (il Nilo), Turchia, Paestum, Pompei, Tunisia, Egitto (Il Cairo), Milano, Genova, Brescia, Ventimiglia, Francia (Borgogna), Albenga, Bobbio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>emilio delfino<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>emilio delfino cartografo<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>3780120005204<\/p>\n","protected":false},"featured_media":158386,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2596,2805],"product_tag":[],"class_list":{"0":"post-63580","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-architecture-design-and-lifestyle","7":"product_cat-logbooks-and-travel-reports","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>diario di viaggio vol. 1 (1996-1997) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"diario di viaggio vol. 1 (1996-1997)\" \/>\n<meta property=\"og:description\" content=\"Author: emilio delfinoPublisher: emilio delfino cartografoISBN: 3780120005204\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T01:30:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/diariodiviaggio1-delfino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"419\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;80,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\\\/\",\"name\":\"diario di viaggio vol. 1 (1996-1997) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/diariodiviaggio1-delfino.jpg\",\"datePublished\":\"2019-02-03T18:03:28+00:00\",\"dateModified\":\"2026-05-09T01:30:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/diariodiviaggio1-delfino.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/diariodiviaggio1-delfino.jpg\",\"width\":419,\"height\":601},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"diario di viaggio vol. 1 (1996-1997)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"80.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"3780120005204\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"diario di viaggio vol. 1 (1996-1997) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/","og_locale":"en_US","og_type":"article","og_title":"diario di viaggio vol. 1 (1996-1997)","og_description":"Author: emilio delfinoPublisher: emilio delfino cartografoISBN: 3780120005204","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T01:30:50+00:00","og_image":[{"width":419,"height":601,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/diariodiviaggio1-delfino.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;80,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/","name":"diario di viaggio vol. 1 (1996-1997) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/diariodiviaggio1-delfino.jpg","datePublished":"2019-02-03T18:03:28+00:00","dateModified":"2026-05-09T01:30:50+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/diariodiviaggio1-delfino.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/diariodiviaggio1-delfino.jpg","width":419,"height":601},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/diario-di-viaggio-vol-1-1996-1997-emilio-delfino-3780120005204\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"diario di viaggio vol. 1 (1996-1997)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"80.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"3780120005204","product_condition":"new"},"df_price":80,"df_sale_price":"","df_regular_price":80,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/diariodiviaggio1-delfino-209x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/63580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=63580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/158386"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=63580"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=63580"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=63580"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=63580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}