{"id":63572,"date":"2019-02-03T19:03:29","date_gmt":"2019-02-03T18:03:29","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/civilt-del-mare-aa-vv-56193064241266\/"},"modified":"2026-05-09T03:30:44","modified_gmt":"2026-05-09T01:30:44","slug":"civilta-del-mare-aa-vv-56193064241266","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/","title":{"rendered":"civilt\u00e0 del mare"},"content":{"rendered":"<p>Questo volume &egrave; un&rsquo;opera ambiziosa e parimenti apprezzabile. Si tratta di una collezione di saggi di natura, tra loro, estremamente diversa e scritti da autori annoverati fra gli esperti italiani, non solo nei propri rispettivi campi di studio. Essi spaziano dalla storia allo sport, fino a descrivere le principali attivit&agrave; che si sviluppano sul mare e dal mare. Naturalmente nessuno di loro ha la pretesa di racchiudere o, addirittura, d&rsquo;interpretare univocamente quelle che sono le infinite realt&agrave; del mare; tutti per&ograve; hanno scritto con spirito di osservazione, di ricerca e secondo un approccio innovativo, che &egrave; sintesi dell&rsquo;uomo che affronta il mare.<\/p>\n<p>Hanno collaborato alla realizzazione dell&#8217;opera:&nbsp;Lega Navale Italiana, Societ&agrave; Geografica Italiana e Ufficio Storico della Marina.<\/p>\n<p>Dettagli tecnici:<\/p>\n<p>&#8211; Volume d&rsquo;alto pregio per contenuti e veste editoriale.<\/p>\n<p>&#8211; Formato chiuso: cm 30x40x10.<\/p>\n<p>&#8211; 480 pagine, oltre 600 iconografie e documenti.<\/p>\n<p>&#8211; Stampa a quattro colori su carta di fabbricazione speciale.<\/p>\n<p>&#8211; Rilegatura artigianale in pelle blu vitello fiore a concia naturale con impressioni in oro a caldo e a secco.<\/p>\n<p>&#8211; Fusione d&rsquo;arte in bronzo sul piatto di coperta del Maestro Remo Carboni.<\/p>\n<p>&#8211; Elegante custodia a conchiglia da biblioteca.<\/p>\n<p>Libro da procurare su richiesta in 15 giorni circa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>la grande storia della marineria italiana<\/p>\n<p class=\"autore\"><span>Author: <\/span>aa.vv.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>progetto editoriale editions<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>56193064241266<\/p>\n","protected":false},"featured_media":133100,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3071,2741],"product_tag":[],"class_list":{"0":"post-63572","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-history-of-seafaring","7":"product_cat-navigation-history","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>civilt\u00e0 del mare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"civilt\u00e0 del mare\" \/>\n<meta property=\"og:description\" content=\"Subtitle: la grande storia della marineria italianaAuthor: aa.vv.Publisher: progetto editoriale editionsISBN: 56193064241266\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T01:30:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/civiltadelmare-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;1.300,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/civilta-del-mare-aa-vv-56193064241266\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/civilta-del-mare-aa-vv-56193064241266\\\/\",\"name\":\"civilt\u00e0 del mare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/civilta-del-mare-aa-vv-56193064241266\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/civilta-del-mare-aa-vv-56193064241266\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/civiltadelmare-2.jpg\",\"datePublished\":\"2019-02-03T18:03:29+00:00\",\"dateModified\":\"2026-05-09T01:30:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/civilta-del-mare-aa-vv-56193064241266\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/civilta-del-mare-aa-vv-56193064241266\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/civilta-del-mare-aa-vv-56193064241266\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/civiltadelmare-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/civiltadelmare-2.jpg\",\"width\":800,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/civilta-del-mare-aa-vv-56193064241266\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"civilt\u00e0 del mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"1300.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"56193064241266\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"civilt\u00e0 del mare - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/","og_locale":"en_US","og_type":"article","og_title":"civilt\u00e0 del mare","og_description":"Subtitle: la grande storia della marineria italianaAuthor: aa.vv.Publisher: progetto editoriale editionsISBN: 56193064241266","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-09T01:30:44+00:00","og_image":[{"width":800,"height":531,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/civiltadelmare-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;1.300,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/","name":"civilt\u00e0 del mare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/civiltadelmare-2.jpg","datePublished":"2019-02-03T18:03:29+00:00","dateModified":"2026-05-09T01:30:44+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/civiltadelmare-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/civiltadelmare-2.jpg","width":800,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/civilta-del-mare-aa-vv-56193064241266\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"civilt\u00e0 del mare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"1300.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"56193064241266","product_condition":"new"},"df_price":1300,"df_sale_price":"","df_regular_price":1300,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/civiltadelmare-2-300x199.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/63572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=63572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/133100"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=63572"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=63572"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=63572"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=63572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}