{"id":63155,"date":"2019-02-03T19:05:27","date_gmt":"2019-02-03T18:05:27","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/"},"modified":"2026-07-11T05:12:27","modified_gmt":"2026-07-11T03:12:27","slug":"isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/","title":{"rendered":"isole dimenticate della laguna di venezia"},"content":{"rendered":"<p>From the foreword: &#8220;This book recounts of all those islands abandoned and then forgotten that once constituted the rich archipelago of the Serenissima Republic. As with the book of the Crovato brothers (&#8220;Isole abbandonate della Laguna di Venezia&#8221; of 1978) this account would like to be a constant reminder of what these islands once were, by again offering on all too seldom discussed subject. These pages are an attempt to rise awareness of how many islands, each with its own story, lie waiting only to be remembered, requalified and, finally, put to use again. Conceived therefore to encourage anyone who so desires, to launch a skiff or a motorboat into the waters now sacrificed to the culture of plastic and to dream of a finding that small lost paradise: the archipelago called Venice&#8221;.<\/p>\n<p>Price of the book &euro; 30,00 + &euro; 7,00 for the delivery at the bookstore.<\/p>\n<p>Languages: English and Italian<\/p>\n<p>Edition: 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>venticinque isole e le loro storie illustrate a mano<\/p>\n<p class=\"autore\"><span>Author: <\/span>lodi t.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>il leggio libreria editrice<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791220010344<\/p>\n","protected":false},"featured_media":135452,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3110,3065,2643],"product_tag":[],"class_list":{"0":"post-63155","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-everything-else-italy-picture-books-tourism","7":"product_cat-maritime-republics","8":"product_cat-veneto-friuli-venezia-giulia-emilia-romagna-and-marche","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>isole dimenticate della laguna di venezia - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"isole dimenticate della laguna di venezia\" \/>\n<meta property=\"og:description\" content=\"Subtitle: venticinque isole e le loro storie illustrate a manoAuthor: lodi t.Publisher: il leggio libreria editriceISBN: 9791220010344\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T03:12:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledimenticatedellalagunadivenezia-lodi-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"457\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;38,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\\\/\",\"name\":\"isole dimenticate della laguna di venezia - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isoledimenticatedellalagunadivenezia-lodi-6.jpg\",\"datePublished\":\"2019-02-03T18:05:27+00:00\",\"dateModified\":\"2026-07-11T03:12:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isoledimenticatedellalagunadivenezia-lodi-6.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isoledimenticatedellalagunadivenezia-lodi-6.jpg\",\"width\":600,\"height\":457},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"isole dimenticate della laguna di venezia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"38.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791220010344\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"isole dimenticate della laguna di venezia - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/","og_locale":"en_US","og_type":"article","og_title":"isole dimenticate della laguna di venezia","og_description":"Subtitle: venticinque isole e le loro storie illustrate a manoAuthor: lodi t.Publisher: il leggio libreria editriceISBN: 9791220010344","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T03:12:27+00:00","og_image":[{"width":600,"height":457,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledimenticatedellalagunadivenezia-lodi-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;38,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/","name":"isole dimenticate della laguna di venezia - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledimenticatedellalagunadivenezia-lodi-6.jpg","datePublished":"2019-02-03T18:05:27+00:00","dateModified":"2026-07-11T03:12:27+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledimenticatedellalagunadivenezia-lodi-6.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledimenticatedellalagunadivenezia-lodi-6.jpg","width":600,"height":457},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-dimenticate-della-laguna-di-venezia-lodi-t-9791220010344\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"isole dimenticate della laguna di venezia"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"38.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9791220010344","product_condition":"new"},"df_price":38,"df_sale_price":"","df_regular_price":38,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isoledimenticatedellalagunadivenezia-lodi-6-300x229.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/63155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=63155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/135452"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=63155"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=63155"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=63155"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=63155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}