{"id":62752,"date":"2021-11-13T13:47:24","date_gmt":"2021-11-13T12:47:24","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/"},"modified":"2026-07-11T01:44:51","modified_gmt":"2026-07-10T23:44:51","slug":"l-uomo-del-fiume-raul-lovisoni-9788856679908","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/","title":{"rendered":"l&#8217;uomo del fiume"},"content":{"rendered":"<p>Raul Lovisoni nella sua vita &egrave; stato molte cose: musicista, insegnante, deputato della Repubblica Italiana, fine pensatore. Ma in questi ultimi anni, dopo essere sopravvissuto a un cancro, &egrave; diventato un uomo che ha riscoperto se stesso abbandonandosi ai ritmi della natura. <strong>Sulle rive dell&#8217;Ausa, in Friuli, e con la sua canoa, Lovisoni risale il fiume della sua infanzia e della sua intera vita<\/strong> e nel farlo tratteggia quella che &egrave; stata un&#8217;esistenza straordinaria, fatta di passioni musicali e politiche, di rivoluzioni e sperimentazioni personali, alla ricerca della verit&agrave; e dell&#8217;essenza della vita. Un Robinson Crusoe contemporaneo che si spoglia del benessere e del cicaleggio delle societ&agrave; contemporanee per abbracciare <strong>il senso profondo dell&#8217;essere<\/strong> al mondo, in mezzo alle <strong>bellezze di Madre Terra<\/strong>.<br \/>Con una <strong>scrittura magnetica e letteraria<\/strong>, pensata come una sinfonia, Raul Lovisoni si fa portatore di un&#8217;esperienza unica e radicale, capace di ponderare e illuminare tutte le riflessioni esistenti riguardo l&#8217;uomo, la natura, il mondo.<\/p>\n<p>Edizione: 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>i pensieri della foce<\/p>\n<p class=\"autore\"><span>Author: <\/span>raul lovisoni<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Piemme (Mondadori Libri)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788856679908<\/p>\n","protected":false},"featured_media":122121,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,2600],"product_tag":[],"class_list":{"0":"post-62752","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-canoeing-rowing-kayaking-and-rafting","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>l&#039;uomo del fiume - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"l&#039;uomo del fiume\" \/>\n<meta property=\"og:description\" content=\"Subtitle: i pensieri della foceAuthor: raul lovisoniPublisher: Piemme (Mondadori Libri)ISBN: 9788856679908\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:44:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/l-uomo-del-fiume-i-pensieri-della-foce-raul-lovisoni-piemme-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"766\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;18,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-uomo-del-fiume-raul-lovisoni-9788856679908\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-uomo-del-fiume-raul-lovisoni-9788856679908\\\/\",\"name\":\"l'uomo del fiume - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-uomo-del-fiume-raul-lovisoni-9788856679908\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-uomo-del-fiume-raul-lovisoni-9788856679908\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/l-uomo-del-fiume-i-pensieri-della-foce-raul-lovisoni-piemme-2.jpg\",\"datePublished\":\"2021-11-13T12:47:24+00:00\",\"dateModified\":\"2026-07-10T23:44:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-uomo-del-fiume-raul-lovisoni-9788856679908\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-uomo-del-fiume-raul-lovisoni-9788856679908\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-uomo-del-fiume-raul-lovisoni-9788856679908\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/l-uomo-del-fiume-i-pensieri-della-foce-raul-lovisoni-piemme-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/l-uomo-del-fiume-i-pensieri-della-foce-raul-lovisoni-piemme-2.jpg\",\"width\":500,\"height\":766},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/l-uomo-del-fiume-raul-lovisoni-9788856679908\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"l&#8217;uomo del fiume\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"18.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788856679908\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"l'uomo del fiume - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/","og_locale":"en_US","og_type":"article","og_title":"l'uomo del fiume","og_description":"Subtitle: i pensieri della foceAuthor: raul lovisoniPublisher: Piemme (Mondadori Libri)ISBN: 9788856679908","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:44:51+00:00","og_image":[{"width":500,"height":766,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/l-uomo-del-fiume-i-pensieri-della-foce-raul-lovisoni-piemme-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;18,50","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/","name":"l'uomo del fiume - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/l-uomo-del-fiume-i-pensieri-della-foce-raul-lovisoni-piemme-2.jpg","datePublished":"2021-11-13T12:47:24+00:00","dateModified":"2026-07-10T23:44:51+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/l-uomo-del-fiume-i-pensieri-della-foce-raul-lovisoni-piemme-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/l-uomo-del-fiume-i-pensieri-della-foce-raul-lovisoni-piemme-2.jpg","width":500,"height":766},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/l-uomo-del-fiume-raul-lovisoni-9788856679908\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"l&#8217;uomo del fiume"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"18.50","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788856679908","product_condition":"new"},"df_price":18.5,"df_sale_price":"","df_regular_price":18.5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/l-uomo-del-fiume-i-pensieri-della-foce-raul-lovisoni-piemme-2-196x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/62752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=62752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/122121"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=62752"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=62752"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=62752"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=62752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}