{"id":62654,"date":"2022-01-20T14:05:48","date_gmt":"2022-01-20T13:05:48","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/"},"modified":"2026-05-09T01:07:35","modified_gmt":"2026-05-08T23:07:35","slug":"procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/","title":{"rendered":"procida ispira"},"content":{"rendered":"<p>La lunga storia, appassionante come un romanzo, delle culture e degli artisti di ogni genere che a Procida, e da Procida, hanno tratto ispirazione.<\/p>\n<p>Una storia fatta di presenze, di innamoramenti, di viaggi e di fughe, di contaminazioni e scoperte.<\/p>\n<p>Questo volume ricostruisce per la prima volta, in modo agile ma rigoroso, e con un ricchissimo apparato iconografico, come l&#8217;isola di Procida sia stata nei secoli un crocevia di linguaggi, stili e architetture. Un contributo prezioso per conoscere la Capitale italiana della Cultura 2022.<\/p>\n<p>Praticamente da sempre Procida &egrave; stata un punto di incontro di culture, luogo di contaminazione, ma anche di ispirazione per artisti, scrittori, poeti, fotografi, registi. Nel 1600 a.C. &egrave; documentata la prima presenza greca, in particolare micenea. Non a caso l&#8217;isola compare in opere dell&#8217;et&agrave; classica, come la <em>Gigantomachia<\/em> di Apollodoro di Atene, o negli scritti del geografo Strabone. Nel 1350 Boccaccio ambienta a Procida una novella del <em>Decamerone<\/em>. Nel Cinquecento &egrave; terra di frontiera nello scontro fra l&#8217;Impero Ottomano e la Lega Santa e sull&#8217;isola appariranno in successione saraceni, aragonesi e borboni. Ognuno lasciando tracce importanti negli scritti e nel territorio.<\/p>\n<p>Poi sar&agrave; la volta del secolo dei lumi e dei Grand Tour, e a Procida approdano viaggiatori da tutto il Nord Europa, come Alphonse de Lamartine, autore di <em>Graziella<\/em>, romanzo simbolo dell&#8217;isola. E infine, nell&#8217;et&agrave; contemporanea, Procida continua a essere luogo di ritrovo e fonte di ispirazione per letterati, artisti, registi, a cominciare ovviamente da Elsa Morante e il suo <em>L&#8217;isola di Arturo<\/em>.<\/p>\n<p>Edizione: 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>un&#8217;isola crocevia di culture<\/p>\n<p class=\"autore\"><span>Author: <\/span>elisabetta montaldo &#8211; donatella pandolfi<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Nutrimenti<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788865948712<\/p>\n","protected":false},"featured_media":153342,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2981,2637],"product_tag":[],"class_list":{"0":"post-62654","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-culture-and-society","7":"product_cat-lazio-campania-and-calabria","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>procida ispira - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"procida ispira\" \/>\n<meta property=\"og:description\" content=\"Subtitle: un&#039;isola crocevia di cultureAuthor: elisabetta montaldo - donatella pandolfiPublisher: NutrimentiISBN: 9788865948712\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:07:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/procida-ispira-montaldo-pandolfi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;16,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\\\/\",\"name\":\"procida ispira - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/procida-ispira-montaldo-pandolfi.jpg\",\"datePublished\":\"2022-01-20T13:05:48+00:00\",\"dateModified\":\"2026-05-08T23:07:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/procida-ispira-montaldo-pandolfi.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/procida-ispira-montaldo-pandolfi.jpg\",\"width\":500,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"procida ispira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"16.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788865948712\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"procida ispira - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/","og_locale":"en_US","og_type":"article","og_title":"procida ispira","og_description":"Subtitle: un'isola crocevia di cultureAuthor: elisabetta montaldo - donatella pandolfiPublisher: NutrimentiISBN: 9788865948712","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:07:35+00:00","og_image":[{"width":500,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/procida-ispira-montaldo-pandolfi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;16,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/","name":"procida ispira - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/procida-ispira-montaldo-pandolfi.jpg","datePublished":"2022-01-20T13:05:48+00:00","dateModified":"2026-05-08T23:07:35+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/procida-ispira-montaldo-pandolfi.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/procida-ispira-montaldo-pandolfi.jpg","width":500,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/procida-ispira-elisabetta-montaldo-donatella-pandolfi-9788865948712\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"procida ispira"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"16.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788865948712","product_condition":"new"},"df_price":16,"df_sale_price":"","df_regular_price":16,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/procida-ispira-montaldo-pandolfi-214x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/62654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=62654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/153342"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=62654"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=62654"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=62654"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=62654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}