{"id":62644,"date":"2022-01-24T16:40:43","date_gmt":"2022-01-24T15:40:43","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/"},"modified":"2026-07-11T01:41:24","modified_gmt":"2026-07-10T23:41:24","slug":"con-la-forza-del-respiro-umberto-pelizzari-9788820068950","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/","title":{"rendered":"con la forza del respiro"},"content":{"rendered":"<p><strong>Cosa pu&ograve; insegnare l&#8217;apnea?<\/strong> Cosa possiamo apprendere dall&#8217;esperienza di un uomo che decide di sfidare le leggi della natura per capire fin dove pu&ograve; arrivare? <strong>Umberto Pelizzari dall&#8217;apnea ha imparato molto<\/strong> e molto continua a imparare e durante <strong>la sua lunga carriera, costellata di record mondiali e successi<\/strong>, non ha fatto altro che misurarsi con i propri limiti per cercare di spostarli un po&#8217; pi&ugrave; in l&agrave;, fedele alla convinzione che qualcosa pu&ograve; apparire impossibile, ma solo finch&eacute; non si dimostra il contrario. Per lui ogni tuffo ha il sapore irresistibile della scoperta, &egrave; un&#8217;occasione per guardarsi dentro e confrontarsi con le speranze, i limiti e le ambizioni.<\/p>\n<p><strong>Nelle pagine di questo libro, ripercorreremo l&#8217;avventura sportiva e umana dell&#8217;autore e leggeremo storie di uomini intraprendenti<\/strong> che sono riusciti a smentire la scienza e le convinzioni diffuse. Ci immergeremo in un mondo affascinante, quasi magico, e <strong>capiremo come il corpo sia in grado di trovare risorse nascoste<\/strong> per adattarsi alle situazioni pi&ugrave; ostili; impareremo a sfruttare la forza di ogni singolo respiro, poich&eacute; i grandi traguardi si raggiungono curando gli aspetti all&#8217;apparenza pi&ugrave; semplici; <strong>comprenderemo come gestire lo stress e le paure<\/strong> senza esserne sovrastati; <strong>coglieremo l&#8217;importanza del lavoro di squadra<\/strong> e di un team per conseguire un obiettivo e fronteggiare gli imprevisti.<\/p>\n<p>E durante questo viaggio, <strong>l&#8217;apnea diventer&agrave; una potentissima metafora della vita capace di parlare a tutti<\/strong>, anche a chi non ha mai indossato una muta per spingersi verso le profondit&agrave; marine. Perch&eacute; tra le imprese di uno tra i pi&ugrave; forti apneisti al mondo e le sfide che ognuno di noi deve affrontare quotidianamente possono esserci davvero moltissimi punti in comune.<\/p>\n<p>Edizione: 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>dal fascino dell&#8217;apnea alle sfide della vita<\/p>\n<p class=\"autore\"><span>Author: <\/span>umberto pelizzari<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>sperling &amp; kupfer<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788820068950<\/p>\n","protected":false},"featured_media":109965,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2584],"product_tag":[],"class_list":{"0":"post-62644","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-diving-apnea-and-snorkeling","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>con la forza del respiro - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"con la forza del respiro\" \/>\n<meta property=\"og:description\" content=\"Subtitle: dal fascino dell&#039;apnea alle sfide della vitaAuthor: umberto pelizzariPublisher: sperling &amp; kupferISBN: 9788820068950\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:41:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/con-la-forza-del-respiro-fascino-apnea-sfide-vita-umberto-pelizzari-sperling-kupfer-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;17,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\\\/\",\"name\":\"con la forza del respiro - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/con-la-forza-del-respiro-fascino-apnea-sfide-vita-umberto-pelizzari-sperling-kupfer-1.jpg\",\"datePublished\":\"2022-01-24T15:40:43+00:00\",\"dateModified\":\"2026-07-10T23:41:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/con-la-forza-del-respiro-fascino-apnea-sfide-vita-umberto-pelizzari-sperling-kupfer-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/con-la-forza-del-respiro-fascino-apnea-sfide-vita-umberto-pelizzari-sperling-kupfer-1.jpg\",\"width\":500,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"con la forza del respiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"17.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788820068950\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"con la forza del respiro - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/","og_locale":"en_US","og_type":"article","og_title":"con la forza del respiro","og_description":"Subtitle: dal fascino dell'apnea alle sfide della vitaAuthor: umberto pelizzariPublisher: sperling &amp; kupferISBN: 9788820068950","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:41:24+00:00","og_image":[{"width":500,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/con-la-forza-del-respiro-fascino-apnea-sfide-vita-umberto-pelizzari-sperling-kupfer-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;17,90","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/","name":"con la forza del respiro - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/con-la-forza-del-respiro-fascino-apnea-sfide-vita-umberto-pelizzari-sperling-kupfer-1.jpg","datePublished":"2022-01-24T15:40:43+00:00","dateModified":"2026-07-10T23:41:24+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/con-la-forza-del-respiro-fascino-apnea-sfide-vita-umberto-pelizzari-sperling-kupfer-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/con-la-forza-del-respiro-fascino-apnea-sfide-vita-umberto-pelizzari-sperling-kupfer-1.jpg","width":500,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/con-la-forza-del-respiro-umberto-pelizzari-9788820068950\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"con la forza del respiro"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"17.90","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788820068950","product_condition":"new"},"df_price":17.9,"df_sale_price":"","df_regular_price":17.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/con-la-forza-del-respiro-fascino-apnea-sfide-vita-umberto-pelizzari-sperling-kupfer-1-214x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/62644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=62644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/109965"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=62644"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=62644"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=62644"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=62644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}