{"id":62508,"date":"2022-04-01T14:22:03","date_gmt":"2022-04-01T12:22:03","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/"},"modified":"2026-05-09T01:05:44","modified_gmt":"2026-05-08T23:05:44","slug":"venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/","title":{"rendered":"venezia, le isole incantate"},"content":{"rendered":"<p>Da Murano a Sottomarina sono <strong>raccontate e disegnate tutte le isole<\/strong> dalle pi&ugrave; note a quelle totalmente dimenticate.<\/p>\n<p>Tante storie si intrecciano e formano la <strong>storia magica, incredibile<\/strong> e ancora poco nota delle tante &#8220;Isole incantate&#8221;. Da <strong>Murano<\/strong> che nel Cinquecento <strong>ospitava trentamila abitanti<\/strong> ridotti ai quattromila di oggi al <strong>Buel del Lovo<\/strong> dove, nel 1797 ultimo anno di vita della Serenissima, c&#8217;era un <strong>fortino in legno per la difesa<\/strong> di Venezia.<\/p>\n<p>Da <strong>Sant&#8217; Erasmo<\/strong> isola agricola, estranea al turismo forsennato e abitata da neppure mille residenti, che continua ad essere l&#8217;<strong>orto di qualit&agrave;<\/strong> di Venezia alla famosa <strong>San Giorgio Maggiore<\/strong> dove ha sede il pi&ugrave; bel <strong>convento benedettino<\/strong> della laguna.<\/p>\n<p>E poi l&#8217;avvincente storia di <strong>San Lazzaro degli Armeni<\/strong>, la piccola Armenia, concessa nel 1717 dalla Repubblica ad un gruppo di monaci Armeni guidati dall&#8217;abate Mechitar (il consolatore) e la gemma lagunare <strong>Poveglia<\/strong> abbandonata da decenni.<\/p>\n<p>Come dimenticare l&#8217;<strong>Isola delle Vignole<\/strong> detta anche &#8220;delle sette vigne&#8221;, data la cultura prevalente della vite e <strong>Burano<\/strong> cos&igrave; bella, delicata e colma di colori pastello&#8230;<\/p>\n<p>Un libro dedicato a coloro che vogliono <strong>uscire dai percorsi &#8220;obbligati&#8221; per andare a vedere e capire le tante &#8220;Piccole Venezie&#8221;.<\/strong><\/p>\n<p>Edizione: 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>luciano menetto &#8211; pierfranco fabris<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>biblioteca dell&#8217;immagine<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788863912821<\/p>\n","protected":false},"featured_media":135610,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3110,2643],"product_tag":[],"class_list":{"0":"post-62508","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-everything-else-italy-picture-books-tourism","7":"product_cat-veneto-friuli-venezia-giulia-emilia-romagna-and-marche","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>venezia, le isole incantate - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"venezia, le isole incantate\" \/>\n<meta property=\"og:description\" content=\"Author: luciano menetto - pierfranco fabrisPublisher: biblioteca dell&#039;immagineISBN: 9788863912821\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:05:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venezia-le-isole-incantate-menetto-fabris-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"856\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;12,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\\\/\",\"name\":\"venezia, le isole incantate - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/venezia-le-isole-incantate-menetto-fabris-6.jpg\",\"datePublished\":\"2022-04-01T12:22:03+00:00\",\"dateModified\":\"2026-05-08T23:05:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/venezia-le-isole-incantate-menetto-fabris-6.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/venezia-le-isole-incantate-menetto-fabris-6.jpg\",\"width\":500,\"height\":856},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"venezia, le isole incantate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"12.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788863912821\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"venezia, le isole incantate - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/","og_locale":"en_US","og_type":"article","og_title":"venezia, le isole incantate","og_description":"Author: luciano menetto - pierfranco fabrisPublisher: biblioteca dell'immagineISBN: 9788863912821","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:05:44+00:00","og_image":[{"width":500,"height":856,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venezia-le-isole-incantate-menetto-fabris-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;12,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/","name":"venezia, le isole incantate - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venezia-le-isole-incantate-menetto-fabris-6.jpg","datePublished":"2022-04-01T12:22:03+00:00","dateModified":"2026-05-08T23:05:44+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venezia-le-isole-incantate-menetto-fabris-6.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venezia-le-isole-incantate-menetto-fabris-6.jpg","width":500,"height":856},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/venezia-le-isole-incantate-luciano-menetto-pierfranco-fabris-9788863912821\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"venezia, le isole incantate"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"12.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788863912821","product_condition":"new"},"df_price":12,"df_sale_price":"","df_regular_price":12,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/venezia-le-isole-incantate-menetto-fabris-6-175x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/62508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=62508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/135610"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=62508"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=62508"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=62508"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=62508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}