{"id":62504,"date":"2022-04-04T16:48:53","date_gmt":"2022-04-04T14:48:53","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/"},"modified":"2026-07-11T01:38:53","modified_gmt":"2026-07-10T23:38:53","slug":"almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/","title":{"rendered":"almanacco navale della seconda guerra mondiale (1939-1945)"},"content":{"rendered":"<p>Il <strong>1&deg; settembre 1939<\/strong>, ottant&rsquo;anni fa, l&rsquo;<strong>attacco tedesco alla Polonia<\/strong> dava il via a quella che in breve tempo sarebbe divenuta la <strong>Seconda Guerra Mondiale. <\/strong>Da subito, <strong>l&rsquo;elemento navale ebbe un ruolo fondamentale<\/strong>. <strong>A sparare i primi colpi<\/strong> della guerra, contro Danzica, era stata <strong>una vecchia corazzata tedesca<\/strong> veterana del precedente conflitto mondiale e, simbolicamente, <strong>la resa<\/strong> del Giappone sarebbe stata firmata, il 2 settembre 1945, <strong>sul ponte di una fiammante corazzata americana<\/strong>.<\/p>\n<p>Questo libro traccia lo <strong>status delle flotte allo scoppio della guerra<\/strong>, al momento del loro coinvolgimento e il loro sviluppo bellico. <strong>Tale ricerca si estende anche alle realt&agrave; minori<\/strong>, quasi sempre tenute in ombra dalla pubblicistica storico-navale: quei Davide che talvolta si batterono contro i Golia avversari, come le <strong>marine finnica e olandese, greca e polacca, tailandese e cinese<\/strong>. Senza contare altri apporti, come quello brasiliano, mentre anche le <strong>marine neutrali<\/strong> dovettero comunque mobilitarsi per <strong>difendere le acque territoriali e gli interessi nazionali<\/strong>.<\/p>\n<p>Edizione: 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>giuliano da fre<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Casa Editrice Odoya<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788862885560<\/p>\n","protected":false},"featured_media":131076,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3051],"product_tag":[],"class_list":{"0":"post-62504","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-from-1919-to-1945","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>almanacco navale della seconda guerra mondiale (1939-1945) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"almanacco navale della seconda guerra mondiale (1939-1945)\" \/>\n<meta property=\"og:description\" content=\"Author: giuliano da frePublisher: Casa Editrice OdoyaISBN: 9788862885560\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:38:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-da-fre-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"514\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;32,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\\\/\",\"name\":\"almanacco navale della seconda guerra mondiale (1939-1945) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-da-fre-3.jpg\",\"datePublished\":\"2022-04-04T14:48:53+00:00\",\"dateModified\":\"2026-07-10T23:38:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-da-fre-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-da-fre-3.jpg\",\"width\":514,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"almanacco navale della seconda guerra mondiale (1939-1945)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"32.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788862885560\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"almanacco navale della seconda guerra mondiale (1939-1945) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/","og_locale":"en_US","og_type":"article","og_title":"almanacco navale della seconda guerra mondiale (1939-1945)","og_description":"Author: giuliano da frePublisher: Casa Editrice OdoyaISBN: 9788862885560","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:38:53+00:00","og_image":[{"width":514,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-da-fre-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;32,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/","name":"almanacco navale della seconda guerra mondiale (1939-1945) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-da-fre-3.jpg","datePublished":"2022-04-04T14:48:53+00:00","dateModified":"2026-07-10T23:38:53+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-da-fre-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-da-fre-3.jpg","width":514,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-giuliano-da-fre-9788862885560\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"almanacco navale della seconda guerra mondiale (1939-1945)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"32.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788862885560","product_condition":"new"},"df_price":32,"df_sale_price":"","df_regular_price":32,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/almanacco-navale-della-seconda-guerra-mondiale-1939-1945-da-fre-3-220x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/62504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=62504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/131076"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=62504"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=62504"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=62504"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=62504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}