{"id":62390,"date":"2022-06-13T14:39:40","date_gmt":"2022-06-13T12:39:40","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/a-summer-on-favignana-elvio-malaspina-9788894542288\/"},"modified":"2026-07-11T01:33:59","modified_gmt":"2026-07-10T23:33:59","slug":"a-summer-on-favignana-elvio-malaspina-9788894542288","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/","title":{"rendered":"a summer on favignana"},"content":{"rendered":"<p><strong>Eolo <\/strong>is <strong>a Genoese Labrador<\/strong> who finds himself spending <strong>his holidays on the island of Favignana<\/strong> at a particularly exciting moment. The local elections are approaching and behind the doors of the Town Hall the mayor and his deputies are struggling to come up with a new strategy for the upcoming campaign. Following an animated and bizarre discussion, the group becomes convinced that the only way to grab the islanders&rsquo; attention is to invite the Maharaja Circus from East India. Yet under the faded big top things are not quite as they seem: the business is on the rocks and the management is altogether incompetent. At least the employees &ndash; who are in fact Italian, and anything other than exotic &ndash; are on the same wavelength as Eolo. Amid sparkling evenings and a few too many drinks, things soon take an unexpected turn, catapulting the ragtag group of friends into a situation that is far from straightforward. A daring adventure lies ahead, and Eolo and his friends will have to draw on every ounce of their kindness and ingenuity. Will they manage to untangle a complicated problem?<\/p>\n<p>Edizione: 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>elvio malaspina<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>aoidos editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788894542288<\/p>\n","protected":false},"featured_media":142628,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2811],"product_tag":[],"class_list":{"0":"post-62390","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-short-stories","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>a summer on favignana - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"a summer on favignana\" \/>\n<meta property=\"og:description\" content=\"Author: elvio malaspinaPublisher: aoidos editoreISBN: 9788894542288\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:33:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/summer-on-favignana-malaspina-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"663\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;12,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-summer-on-favignana-elvio-malaspina-9788894542288\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-summer-on-favignana-elvio-malaspina-9788894542288\\\/\",\"name\":\"a summer on favignana - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-summer-on-favignana-elvio-malaspina-9788894542288\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-summer-on-favignana-elvio-malaspina-9788894542288\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/summer-on-favignana-malaspina-2.jpg\",\"datePublished\":\"2022-06-13T12:39:40+00:00\",\"dateModified\":\"2026-07-10T23:33:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-summer-on-favignana-elvio-malaspina-9788894542288\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-summer-on-favignana-elvio-malaspina-9788894542288\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-summer-on-favignana-elvio-malaspina-9788894542288\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/summer-on-favignana-malaspina-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/summer-on-favignana-malaspina-2.jpg\",\"width\":440,\"height\":663},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-summer-on-favignana-elvio-malaspina-9788894542288\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"a summer on favignana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"12.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788894542288\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"a summer on favignana - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/","og_locale":"en_US","og_type":"article","og_title":"a summer on favignana","og_description":"Author: elvio malaspinaPublisher: aoidos editoreISBN: 9788894542288","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:33:59+00:00","og_image":[{"width":440,"height":663,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/summer-on-favignana-malaspina-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;12,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/","name":"a summer on favignana - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/summer-on-favignana-malaspina-2.jpg","datePublished":"2022-06-13T12:39:40+00:00","dateModified":"2026-07-10T23:33:59+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/summer-on-favignana-malaspina-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/summer-on-favignana-malaspina-2.jpg","width":440,"height":663},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-summer-on-favignana-elvio-malaspina-9788894542288\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"a summer on favignana"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"12.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788894542288","product_condition":"new"},"df_price":12,"df_sale_price":"","df_regular_price":12,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/summer-on-favignana-malaspina-2-199x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/62390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=62390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/142628"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=62390"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=62390"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=62390"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=62390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}