{"id":62352,"date":"2022-06-20T12:54:31","date_gmt":"2022-06-20T10:54:31","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/"},"modified":"2026-07-11T01:31:44","modified_gmt":"2026-07-10T23:31:44","slug":"il-sabir-dei-pirati-federico-de-ambrosis-9788831304849","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/","title":{"rendered":"il sabir dei pirati"},"content":{"rendered":"<p>Attraverso <strong>1001 aneddoti<\/strong>, questo libro propone una <strong>ricostruzione storica dei fatti di pirateria e guerra di corsa<\/strong> avvenuti nelle acque del <strong>Mediterraneo <\/strong>tra il <strong>1536 <\/strong>e il <strong>1574<\/strong>. La parabola umana di <strong>Giovanni Dionigi Galeni<\/strong>, <strong>sequestrato <\/strong>da ragazzino a Isola di Capo Rizzuto e destinato, dopo la conversione, a una <strong>folgorante carriera nella marina turca<\/strong>, si dirama in altri <strong>quattro filoni narrativi<\/strong> dedicati ai coprotagonisti e alle scenografie di questa storia sconosciuta ai pi&ugrave;.<\/p>\n<p>&#8220;<em>La quantit&agrave; di fatti, aneddoti e avvenimenti che Federico ha prima catalogato e poi narrato &egrave; incredibile. Ha ricostruito un intero mondo di cui avevamo perso traccia. Questo &egrave; l&#8217;equivalente di Star Wars della storia della pirateria del Mediterraneo.<\/em>&#8221; Massimo Roccaforte<\/p>\n<p>Edizione: 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>1001 vicende della guerra di corsa nel mediterraneo<\/p>\n<p class=\"autore\"><span>Author: <\/span>federico de ambrosis<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>prospero editore<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788831304849<\/p>\n","protected":false},"featured_media":132757,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3044,3063],"product_tag":[],"class_list":{"0":"post-62352","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-essays-modern-era","7":"product_cat-essays-books-navigation-history-pirates","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>il sabir dei pirati - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"il sabir dei pirati\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 1001 vicende della guerra di corsa nel mediterraneoAuthor: federico de ambrosisPublisher: prospero editoreISBN: 9788831304849\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:31:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sabir-dei-pirati-de-ambrosis-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;25,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\\\/\",\"name\":\"il sabir dei pirati - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sabir-dei-pirati-de-ambrosis-2.jpg\",\"datePublished\":\"2022-06-20T10:54:31+00:00\",\"dateModified\":\"2026-07-10T23:31:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sabir-dei-pirati-de-ambrosis-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sabir-dei-pirati-de-ambrosis-2.jpg\",\"width\":500,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"il sabir dei pirati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"25.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788831304849\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"il sabir dei pirati - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/","og_locale":"en_US","og_type":"article","og_title":"il sabir dei pirati","og_description":"Subtitle: 1001 vicende della guerra di corsa nel mediterraneoAuthor: federico de ambrosisPublisher: prospero editoreISBN: 9788831304849","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:31:44+00:00","og_image":[{"width":500,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sabir-dei-pirati-de-ambrosis-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;25,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/","name":"il sabir dei pirati - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sabir-dei-pirati-de-ambrosis-2.jpg","datePublished":"2022-06-20T10:54:31+00:00","dateModified":"2026-07-10T23:31:44+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sabir-dei-pirati-de-ambrosis-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sabir-dei-pirati-de-ambrosis-2.jpg","width":500,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/il-sabir-dei-pirati-federico-de-ambrosis-9788831304849\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"il sabir dei pirati"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"25.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9788831304849","product_condition":"new"},"df_price":25,"df_sale_price":"","df_regular_price":25,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sabir-dei-pirati-de-ambrosis-2-214x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/62352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=62352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/132757"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=62352"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=62352"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=62352"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=62352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}