{"id":61650,"date":"2022-07-11T18:24:18","date_gmt":"2022-07-11T16:24:18","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/"},"modified":"2026-07-11T01:28:04","modified_gmt":"2026-07-10T23:28:04","slug":"vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/","title":{"rendered":"vita, avventure e piraterie del capitano singleton"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione di Rizzoli Editore del 1959 in ottimo stato di conservazione, edizione &ldquo;Biblioteca Universale Rizzoli&rdquo; 1484-1486 (volume triplo). In-16, brossura (con le prime segnature danneggiate al piede nei pressi del dorso); 280 pp. ingiallite, con ex libris di Emilio Delfino e annotazione in matita a pag. 1.<\/strong><\/p>\n<p><strong>Traduzione e introduzione di Giorgio Spina.<\/strong><\/p>\n<p>Dalla nota introduttiva: Vita, avventure e piraterie del capitano Singleton&nbsp;<em>(<\/em>The Life, Adventures and Piracies of Captain Singleton<em>), apparso [&#8230;] nel 1720, &egrave; [&#8230;] un romanzo narrato in prima persona. Il protagonista rivive gli episodi salienti della sua vita avventurosa di pirata e filibustiere, risalendo alle origini: da quando, ancor bambinello, &egrave; rapito ai legittimi genitori per passare nelle mani di megere vagabonde e sfruttatrici. Privo di educazione della mente e dello spirito, batte i mari a bordo di un veliero portoghese e, compromesso in un ammutinamento, viene abbandonato con alcuni marinai sulle coste del Madagascar. Di l&agrave; cominciano le peripezie del giovinetto, che segue i compagni in un estenuante viaggio attraverso il Continente Nero, dalle sponde orientali a quelle occidentali, alla ricerca di una via per il ritorno. Le descrizioni dell&#8217;ambiente africano costituiscono la particolarit&agrave; pi&ugrave; significativa di questa prima parte del libro, e, pur essendo pi&ugrave; frutto d&#8217;immaginazione &#8211; o d&#8217;intuizione &#8211; che di vera conoscenza, fissano con suggestiva icasticit&agrave; la realt&agrave; quale apparve agli esploratori dell&#8217;Ottocento.<\/em><\/p>\n<p><em>Il seguito della narrazione presenta un Singleton in piena attivit&agrave; di corsaro. Le sue gesta spaziano dalle coste dell&#8217;America meridionale a quelle dell&#8217;India, ai mari della Sonda, su su, fino alle Filippine e alle acque di Formosa. Campeggia in questa seconda parte del romanzo la forte personalit&agrave; di William il quacchero, consigliere, amico e poi guida spirituale di Singleton. Cos&igrave; la figura del pirata &#8211; torva, spietata e spavalda quale dovrebbe essere &#8211; si stempera fino a diventare, a mano a mano, quello di un povero infelice, traviato dalla malasorte, che si dibatte per liberare dalla dura scorza d&#8217;una vita sciagurata la voce della coscienza e i palpiti del cuore; e l&#8217;avventura cede il passo ai problemi dello spirito, il pirata si tramuta in penitente teso verso il sereno approdo alla purificazione.<\/em><\/p>\n<p><em>Come tutta la narrativa del De Foe, anche questo romanzo non &egrave; certo immune di pecche formali: incongruenze psicologiche, anacronismi, contraddizioni; scorie di una vocazione pi&ugrave; istintiva che controllata, che portava l&#8217;autore a una scrittura di getto, impetuosa come l&#8217;animo dei suoi personaggi, sulla quale non gli era possibile di tornare e porvi ordine, una volta scuotatavi tutta la sua ansia. Ma, dunque, una sponteneit&agrave;, un&#8217;immediatezza e un&#8217;aderenza alla realt&agrave; che sono i pregi maggiori del De Foe.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>daniel defoe<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>bur (rizzoli)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1657556656<\/p>\n","protected":false},"featured_media":142560,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,3061,2607],"product_tag":[],"class_list":{"0":"post-61650","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-narrative-books-navigation-history-pirates","8":"product_cat-narrative","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>vita, avventure e piraterie del capitano singleton - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"vita, avventure e piraterie del capitano singleton\" \/>\n<meta property=\"og:description\" content=\"Author: daniel defoePublisher: bur (rizzoli)ISBN: LDM1657556656\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:28:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-bur-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"786\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\\\/\",\"name\":\"vita, avventure e piraterie del capitano singleton - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-bur-5.jpg\",\"datePublished\":\"2022-07-11T16:24:18+00:00\",\"dateModified\":\"2026-07-10T23:28:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-bur-5.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-bur-5.jpg\",\"width\":512,\"height\":786},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"vita, avventure e piraterie del capitano singleton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1657556656\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"vita, avventure e piraterie del capitano singleton - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/","og_locale":"en_US","og_type":"article","og_title":"vita, avventure e piraterie del capitano singleton","og_description":"Author: daniel defoePublisher: bur (rizzoli)ISBN: LDM1657556656","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:28:04+00:00","og_image":[{"width":512,"height":786,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-bur-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/","name":"vita, avventure e piraterie del capitano singleton - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-bur-5.jpg","datePublished":"2022-07-11T16:24:18+00:00","dateModified":"2026-07-10T23:28:04+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-bur-5.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-bur-5.jpg","width":512,"height":786},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-ldm1657556656\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"vita, avventure e piraterie del capitano singleton"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1657556656","product_condition":"new"},"df_price":19,"df_sale_price":"","df_regular_price":19,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/vita-avventure-e-piraterie-del-capitano-singleton-daniel-defoe-bur-5-195x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/61650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=61650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/142560"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=61650"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=61650"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=61650"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=61650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}