{"id":61134,"date":"2022-07-02T17:10:23","date_gmt":"2022-07-02T15:10:23","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/"},"modified":"2026-07-11T01:29:12","modified_gmt":"2026-07-10T23:29:12","slug":"le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/","title":{"rendered":"le piovre (le esplorazioni sottomarine di jacques-yves cousteau\u00a7)"},"content":{"rendered":"<p><strong>Raro esemplare della seconda edizione di Longanesi &amp; C. del 1972 stampato nel settembre 1974 in ottimo stato di conservazione, collezione diretta da Gianni Brera &ldquo;La vostra via sportiva&rdquo; 31, serie &#8220;Le esplorazioni sottomarine di Jacques-Yves-Cousteau&#8221;. In-8, legatura editoriale telata blu con impressioni oro al dorso; sovraccoperta in carta (ingiallita, con qualche segno del tempo e strappo in prima al taglio superiore) illustrata a colori con alette; 304 pp., con 51 illustrazioni e 6 cartine in nero e 124 fotografie a colori nel testo.<\/strong><\/p>\n<p><strong>Traduzione di Elena Bona.<\/strong><\/p>\n<p>Dall&#8217;aletta anteriore:&nbsp;<em>L&#8217;ormai celebre crociera della <\/em>Calypso<em>, che si pu&ograve; considerare come una moderna odissea sottomarina, &egrave; stata il punto culminante del pioniere delle esplorazioni del fondo degli oceani, che ha potuto cos&igrave; riassumere, provare e documentare in modo definitivo quanto aveva gi&agrave; intravisto durante lunghi anni dedicati a un mondo meraviglioso e denso di sorprese. Dopo averci spiegato tutto sullo squalo, la balena, i coralli e i tesori sommersi, eccolo intento ad affrontare col suo solito efficacissimo realismo, superiore a qualsiasi narrazione fantastica, gli incontri con le piovre. Per molte centinaia di anni, questi polpi giganteschi sono stati descritti come mostri feroci, capaci di strangolare un uomo, addirittura di trascinare al fondo imbarcazioni. Tali immagini sono state alimentate di continuo, fino ai giorni nostri, ma soprattutto nel secolo scorso. Due richiami precisi: la piovra descritta da Victor Hugo, che impegna il destino di un uomo in una lotta spietata, e quelle descritte da Jules Verne, che avvolgono il&nbsp;<\/em>Nautilus&nbsp;<em>e tentano di espugnarlo come una fortezza. Il comandante Cousteau, invece, forse perch&eacute; si muove nel loro ambiente naturale quasi con perfetta disinvoltura, riabilita una volta per sempre queste strane creature che, al contrario di quanto si pensa, sono timide, pronte ai giochi, molto intelligenti, e, se prese per il loro verso, addirittura amichevoli. In un&#8217;affascinante narrazione, accompagnata da 124 fotografie a colori, Cousteau illustra i suoi appuntamenti con&nbsp;<\/em>i tentacoli dell&#8217;intelligenza<em> nella baia di una piccola isola dove un polpo spunta da ogni roccia; poi in una zona archeologica del Mediterraneo dove intere colonie vivono in antiche anfore greche; al largo della costa di Seattle dove vivono le piovre pi&ugrave; gigantesche; e infine ci racconta una memorabile notte nel Pacifico, quando si ritrova spettatore degli amori di migliaia di calamari. Seguono poi altre avventure, e le spiegazioni pi&ugrave; chiare e pi&ugrave; semplici sugli organismi dei cefalopodi.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>jacques-yves cousteau &#8211; philippe diol\u00e9<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>longanesi <\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1656774622<\/p>\n","protected":false},"featured_media":141692,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2805,2997,2589,2608],"product_tag":[],"class_list":{"0":"post-61134","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-logbooks-and-travel-reports","7":"product_cat-narrative-narrative-and-essays","8":"product_cat-books-diving-literature","9":"product_cat-reports-and-essays","11":"first","12":"outofstock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>le piovre (le esplorazioni sottomarine di jacques-yves cousteau\u00a7) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"le piovre (le esplorazioni sottomarine di jacques-yves cousteau\u00a7)\" \/>\n<meta property=\"og:description\" content=\"Author: jacques-yves cousteau - philippe diol\u00e9Publisher: longanesi ISBN: LDM1656774622\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:29:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/le-piovre-jacques-yves-cousteau-philippe-diole-longanesi-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"525\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;35,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\\\/\",\"name\":\"le piovre (le esplorazioni sottomarine di jacques-yves cousteau\u00a7) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/le-piovre-jacques-yves-cousteau-philippe-diole-longanesi-3.jpg\",\"datePublished\":\"2022-07-02T15:10:23+00:00\",\"dateModified\":\"2026-07-10T23:29:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/le-piovre-jacques-yves-cousteau-philippe-diole-longanesi-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/le-piovre-jacques-yves-cousteau-philippe-diole-longanesi-3.jpg\",\"width\":525,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"le piovre (le esplorazioni sottomarine di jacques-yves cousteau\u00a7)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"35.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1656774622\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"le piovre (le esplorazioni sottomarine di jacques-yves cousteau\u00a7) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/","og_locale":"en_US","og_type":"article","og_title":"le piovre (le esplorazioni sottomarine di jacques-yves cousteau\u00a7)","og_description":"Author: jacques-yves cousteau - philippe diol\u00e9Publisher: longanesi ISBN: LDM1656774622","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:29:12+00:00","og_image":[{"width":525,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/le-piovre-jacques-yves-cousteau-philippe-diole-longanesi-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;35,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/","name":"le piovre (le esplorazioni sottomarine di jacques-yves cousteau\u00a7) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/le-piovre-jacques-yves-cousteau-philippe-diole-longanesi-3.jpg","datePublished":"2022-07-02T15:10:23+00:00","dateModified":"2026-07-10T23:29:12+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/le-piovre-jacques-yves-cousteau-philippe-diole-longanesi-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/le-piovre-jacques-yves-cousteau-philippe-diole-longanesi-3.jpg","width":525,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/le-piovre-le-esplorazioni-sottomarine-di-jacques-yves-cousteau-jacques-yves-cousteau-philippe-diole-ldm1656774622\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"le piovre (le esplorazioni sottomarine di jacques-yves cousteau\u00a7)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"35.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1656774622","product_condition":"new"},"df_price":35,"df_sale_price":"","df_regular_price":35,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/le-piovre-jacques-yves-cousteau-philippe-diole-longanesi-3-225x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/61134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=61134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/141692"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=61134"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=61134"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=61134"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=61134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}