{"id":61042,"date":"2022-07-01T14:44:21","date_gmt":"2022-07-01T12:44:21","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/"},"modified":"2026-07-11T01:29:41","modified_gmt":"2026-07-10T23:29:41","slug":"sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/","title":{"rendered":"sola intorno al mondo"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione di Longnesi &amp; C. del 2001 in perfetto stato di conservazione, collana &ldquo;Il cammeo&rdquo; 375. In-8, legatura editoriale telata marrone con incisioni oro al dorso; sovraccoperta in carta illustrata a colori con alette; 272 pp. ingiallite, con dedica di Isabelle Autissier all&#8217;occhiello; con alcune illustrazioni in nero nel testo e 8 tavole fotografiche a colori fuori testo.<\/strong><\/p>\n<p><strong>Traduzione di Francesco Bruno.<\/strong><\/p>\n<p><strong>Prefazioni di G&eacute;rard Janichon e J&eacute;rome Poncet.<\/strong><\/p>\n<p>Dall&#8217;aletta anteriore: <em>Forse ce ne saranno altri, di Horn, belli, collerici, teneri. Soltanto il primo Horn, per&ograve;, &egrave; quello buono. E&#8217; segno che un giorno si &egrave; dato del tu al proprio sogno, che si &egrave; saputo arrivare fin qui, in questo capo del mondo dove immaginario e realt&agrave; s&#8217;incontrano. <\/em>Il sogno di Isabelle Autissier, la prima donna ad aver compiuto un giro del mondo in solitario a bordo di una barca a vela, cominci&ograve; nel 1987, quando prese parte alla sua prima regata, la Mini-Transat, una transatlantica in due tappe riservata a barche di sei metri e mezzo: vinse la prima tappa e concluse al terzo posto in classifica generale. Da allora, tappa dopo tappa, da un oceano all&rsquo;altro, ha scritto la propria storia di mare e di vita partecipando a molte altre competizioni, che l&rsquo;hanno fatta diventare la pi&ugrave; famosa navigatrice solitaria al mondo. Questo libro &egrave; il racconto della sua avventura: un racconto a due voci, quella della Autissier e quella di Eric Coquerel, in cui si alternano emozioni, lacrime e sorrisi, momenti inebrianti e cocenti delusioni. Perch&eacute; la regata in solitario &#8211; oltre che un privilegio &#8211; &egrave; un esercizio severo e impone un confronto con la natura che non ammette deroghe o compromessi. Il mare acuisce i sensi, restituisce intatto il piacere delle cose semplici: il riflesso di una nuvola, il colore dell&#8217;acqua, il volo di un uccello. Come se tra il vento e l&#8217;orizzonte si tornasse all&#8217;alba del mondo, al mistero, all&#8217;armonia dell&#8217;inizio. Il mare insegna a guardare pi&ugrave; a fondo nelle increspature dell&#8217;anima, a capire meglio, a vivere meglio. Queste pagine (corredate di numerose fotografie a colori), ricche di informazioni tecniche utilissime agli appassionati di vela, parlano di vittorie, sconfitte, incidenti e naufragi, ma c&#8217;&egrave; qualcosa che va al di l&agrave; della cronaca sportiva e parla di sacrifici, dedizione, disciplina, della gioia di tornare a terra e ritrovare gli amici, della voglia di ripartire, per assaporare ancora una volta <em>il sale delle cose ordinarie<\/em>. Isabelle Autissier continuer&agrave; a farlo, <em>sola intorno al mondo<\/em>, sino a quando la scintilla che la muove s&#8217;infiammer&agrave;, nelle giornate di gran vento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>isabelle autissier &#8211; eric coquerel<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>longanesi <\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788830417991<\/p>\n","protected":false},"featured_media":121560,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2803,2805,2607],"product_tag":[],"class_list":{"0":"post-61042","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-biography-and-memories","7":"product_cat-logbooks-and-travel-reports","8":"product_cat-narrative","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>sola intorno al mondo - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sola intorno al mondo\" \/>\n<meta property=\"og:description\" content=\"Author: isabelle autissier - eric coquerelPublisher: longanesi ISBN: 9788830417991\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:29:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-longanesi-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"521\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;29,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\\\/\",\"name\":\"sola intorno al mondo - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-longanesi-4.jpg\",\"datePublished\":\"2022-07-01T12:44:21+00:00\",\"dateModified\":\"2026-07-10T23:29:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-longanesi-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-longanesi-4.jpg\",\"width\":521,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"sola intorno al mondo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"29.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788830417991\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"sola intorno al mondo - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/","og_locale":"en_US","og_type":"article","og_title":"sola intorno al mondo","og_description":"Author: isabelle autissier - eric coquerelPublisher: longanesi ISBN: 9788830417991","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:29:41+00:00","og_image":[{"width":521,"height":720,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-longanesi-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;29,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/","name":"sola intorno al mondo - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-longanesi-4.jpg","datePublished":"2022-07-01T12:44:21+00:00","dateModified":"2026-07-10T23:29:41+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-longanesi-4.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-longanesi-4.jpg","width":521,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-9788830417991\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"sola intorno al mondo"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"29.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"9788830417991","product_condition":"new"},"df_price":29,"df_sale_price":"","df_regular_price":29,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sola-intorno-al-mondo-isabelle-autissier-eric-coquerel-longanesi-4-217x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/61042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=61042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/121560"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=61042"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=61042"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=61042"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=61042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}