{"id":59349,"date":"2020-12-08T15:35:41","date_gmt":"2020-12-08T14:35:41","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/"},"modified":"2026-05-09T01:20:13","modified_gmt":"2026-05-08T23:20:13","slug":"framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/","title":{"rendered":"framed print &#8220;wind rose &#8211; tabula indicans nomina 32 ventorum&#8221;"},"content":{"rendered":"<p>This reproduction of an antique print was hand-engraved on fine paper and hand watercolored by expert painters.<\/p>\n<p>Frame in red shaded ivory wood and glass.<\/p>\n<p>Handcrafted product.<\/p>\n<p>Made in Italy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>61&#215;61 cm<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>la casa della stampa<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>78496522872995BIS<\/p>\n","protected":false},"featured_media":120129,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2444],"product_tag":[],"class_list":{"0":"post-59349","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-wind-roses-framed-wall-items","7":"product_shipping_class-packaging","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>framed print &quot;wind rose - tabula indicans nomina 32 ventorum&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"framed print &quot;wind rose - tabula indicans nomina 32 ventorum&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 61x61 cmManufacturer: la casa della stampaISBN: 78496522872995BIS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:20:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-78496522872995bis-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;230,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\\\/\",\"name\":\"framed print \\\"wind rose - tabula indicans nomina 32 ventorum\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-rosa-dei-venti-78496522872995bis-4.jpg\",\"datePublished\":\"2020-12-08T14:35:41+00:00\",\"dateModified\":\"2026-05-08T23:20:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-rosa-dei-venti-78496522872995bis-4.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-rosa-dei-venti-78496522872995bis-4.jpg\",\"width\":630,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"framed print &#8220;wind rose &#8211; tabula indicans nomina 32 ventorum&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"230.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"78496522872995BIS\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"framed print \"wind rose - tabula indicans nomina 32 ventorum\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/","og_locale":"en_US","og_type":"article","og_title":"framed print \"wind rose - tabula indicans nomina 32 ventorum\"","og_description":"Subtitle: 61x61 cmManufacturer: la casa della stampaISBN: 78496522872995BIS","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:20:13+00:00","og_image":[{"width":630,"height":628,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-78496522872995bis-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;230,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/","name":"framed print \"wind rose - tabula indicans nomina 32 ventorum\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-78496522872995bis-4.jpg","datePublished":"2020-12-08T14:35:41+00:00","dateModified":"2026-05-08T23:20:13+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-78496522872995bis-4.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-78496522872995bis-4.jpg","width":630,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-wind-rose-tabula-indicans-nomina-32-ventorum-78496522872995bis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"framed print &#8220;wind rose &#8211; tabula indicans nomina 32 ventorum&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"230.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"78496522872995BIS","product_condition":"new"},"df_price":230,"df_sale_price":"","df_regular_price":230,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-78496522872995bis-4-300x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/59349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=59349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/120129"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=59349"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=59349"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=59349"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=59349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}