{"id":58680,"date":"2021-05-25T16:25:10","date_gmt":"2021-05-25T14:25:10","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/"},"modified":"2026-07-11T01:36:16","modified_gmt":"2026-07-10T23:36:16","slug":"cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/","title":{"rendered":"cabo de sao vicente to faro n. 89 (2015)"},"content":{"rendered":"<p>Nautical chart by the British Admiralty published in 2010. The copy available to us was reprinted and updated in 2015.<\/p>\n<p>No longer suitable for navigation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>106&#215;71 cm<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>united kingdom hydrographic office (ukho)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>UKHO89BIS<\/p>\n","protected":false},"featured_media":58678,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2460],"product_tag":[],"class_list":{"0":"post-58680","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-not-to-be-used-for-navigation","7":"product_shipping_class-formato-spedizione","9":"first","10":"instock","11":"sale","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>cabo de sao vicente to faro n. 89 (2015) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cabo de sao vicente to faro n. 89 (2015)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 106x71 cmManufacturer: united kingdom hydrographic office (ukho)ISBN: UKHO89BIS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T23:36:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cabo-de-sao-vicente-to-faro-n-89-ukho.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"201\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;30,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\\\/\",\"name\":\"cabo de sao vicente to faro n. 89 (2015) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/cabo-de-sao-vicente-to-faro-n-89-ukho.jpg\",\"datePublished\":\"2021-05-25T14:25:10+00:00\",\"dateModified\":\"2026-07-10T23:36:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/cabo-de-sao-vicente-to-faro-n-89-ukho.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/cabo-de-sao-vicente-to-faro-n-89-ukho.jpg\",\"width\":300,\"height\":201},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"cabo de sao vicente to faro n. 89 (2015)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"30.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"UKHO89BIS\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"cabo de sao vicente to faro n. 89 (2015) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/","og_locale":"en_US","og_type":"article","og_title":"cabo de sao vicente to faro n. 89 (2015)","og_description":"Subtitle: 106x71 cmManufacturer: united kingdom hydrographic office (ukho)ISBN: UKHO89BIS","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T23:36:16+00:00","og_image":[{"width":300,"height":201,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cabo-de-sao-vicente-to-faro-n-89-ukho.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;30,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/","name":"cabo de sao vicente to faro n. 89 (2015) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cabo-de-sao-vicente-to-faro-n-89-ukho.jpg","datePublished":"2021-05-25T14:25:10+00:00","dateModified":"2026-07-10T23:36:16+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cabo-de-sao-vicente-to-faro-n-89-ukho.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cabo-de-sao-vicente-to-faro-n-89-ukho.jpg","width":300,"height":201},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/cabo-de-sao-vicente-to-faro-n-89-2015-ukho89bis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"cabo de sao vicente to faro n. 89 (2015)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"30.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"UKHO89BIS","product_condition":"new"},"df_price":30,"df_sale_price":30,"df_regular_price":67,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/cabo-de-sao-vicente-to-faro-n-89-ukho.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/58680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=58680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/58678"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=58680"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=58680"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=58680"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=58680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}