{"id":55644,"date":"2022-01-24T13:22:50","date_gmt":"2022-01-24T12:22:50","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776bis\/"},"modified":"2026-05-09T01:07:28","modified_gmt":"2026-05-08T23:07:28","slug":"framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/","title":{"rendered":"framed print &#8220;windrose on ancient book page &#8211; tabula indicans nomina 32 ventorum&#8221;"},"content":{"rendered":"<p style=\"text-align: justify\">Reproduction of an antique print engraved with a hand press and watercolored by expert painters on ancient book pages.<\/p>\n<p style=\"text-align: justify\">Wooden double glass frame.<\/p>\n<p style=\"text-align: justify\">Handcrafted product made in Italy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>28,5&#215;36,5 cm<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>la casa della stampa<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1639144776Q<\/p>\n","protected":false},"featured_media":159638,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2444],"product_tag":[],"class_list":{"0":"post-55644","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-wind-roses-framed-wall-items","7":"product_shipping_class-packaging","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>framed print &quot;windrose on ancient book page - tabula indicans nomina 32 ventorum&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"framed print &quot;windrose on ancient book page - tabula indicans nomina 32 ventorum&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 28,5x36,5 cmManufacturer: la casa della stampaISBN: LDM1639144776Q\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:07:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-su-carta-antica-ldm1639144776bis-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"541\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;118,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\\\/\",\"name\":\"framed print \\\"windrose on ancient book page - tabula indicans nomina 32 ventorum\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-rosa-dei-venti-su-carta-antica-ldm1639144776bis-3.jpg\",\"datePublished\":\"2022-01-24T12:22:50+00:00\",\"dateModified\":\"2026-05-08T23:07:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-rosa-dei-venti-su-carta-antica-ldm1639144776bis-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-rosa-dei-venti-su-carta-antica-ldm1639144776bis-3.jpg\",\"width\":541,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"framed print &#8220;windrose on ancient book page &#8211; tabula indicans nomina 32 ventorum&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"118.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1639144776Q\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"framed print \"windrose on ancient book page - tabula indicans nomina 32 ventorum\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/","og_locale":"en_US","og_type":"article","og_title":"framed print \"windrose on ancient book page - tabula indicans nomina 32 ventorum\"","og_description":"Subtitle: 28,5x36,5 cmManufacturer: la casa della stampaISBN: LDM1639144776Q","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:07:28+00:00","og_image":[{"width":541,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-su-carta-antica-ldm1639144776bis-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;118,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/","name":"framed print \"windrose on ancient book page - tabula indicans nomina 32 ventorum\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-su-carta-antica-ldm1639144776bis-3.jpg","datePublished":"2022-01-24T12:22:50+00:00","dateModified":"2026-05-08T23:07:28+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-su-carta-antica-ldm1639144776bis-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-su-carta-antica-ldm1639144776bis-3.jpg","width":541,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-windrose-on-ancient-book-page-tabula-indicans-nomina-32-ventorum-ldm1639144776q\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"framed print &#8220;windrose on ancient book page &#8211; tabula indicans nomina 32 ventorum&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"118.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"LDM1639144776Q","product_condition":"new"},"df_price":118,"df_sale_price":"","df_regular_price":118,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-rosa-dei-venti-su-carta-antica-ldm1639144776bis-3-232x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/55644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=55644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/159638"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=55644"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=55644"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=55644"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=55644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}