{"id":54832,"date":"2021-12-03T15:07:36","date_gmt":"2021-12-03T14:07:36","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/aquatic-cratures-white-artwork-pinocchio-riccardo-capuzzo-ldm1638540455\/"},"modified":"2026-05-09T01:08:58","modified_gmt":"2026-05-08T23:08:58","slug":"pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/","title":{"rendered":"pinocchio white artwork (whales collection)"},"content":{"rendered":"<p><em>&#8220;This illustration represent <strong>the famous Carlo Collodi fairy tale <\/strong><\/em><strong>Pinocchio<\/strong><em>.<\/em><\/p>\n<p><em>All <strong>illustrations <\/strong>are <strong>hand-made using a pencil<\/strong> and then refined with China ink. A <strong>high-resolution scan<\/strong> follows, to faithfully maintain the visual characteristics of the hand drawing&rdquo;<\/em>. <strong>Riccardo Capuzzo<\/strong><\/p>\n<p>This photo print is precisely <strong>laminated to the acrylic glass<\/strong> and sealed with an <strong>aluminium base<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>40&#215;60 cm<\/p>\n<p class=\"autore\"><span>Author: <\/span>riccardo capuzzo<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>aquatic creatures<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1638540455<\/p>\n","protected":false},"featured_media":144229,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2409,2443,2900],"product_tag":[],"class_list":{"0":"post-54832","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-home-design-marine-decor","7":"product_cat-literary-framework","8":"product_cat-marine-mammals-marine-biology","9":"product_shipping_class-packaging","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>pinocchio white artwork (whales collection) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pinocchio white artwork (whales collection)\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 40x60 cmAuthor: riccardo capuzzoManufacturer: aquatic creaturesISBN: LDM1638540455\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:08:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/artworks-bianco-balena-pinocchio-40x60-aquatic-creatures-capuzzo-15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"525\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;230,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\\\/\",\"name\":\"pinocchio white artwork (whales collection) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/artworks-bianco-balena-pinocchio-40x60-aquatic-creatures-capuzzo-15.jpg\",\"datePublished\":\"2021-12-03T14:07:36+00:00\",\"dateModified\":\"2026-05-08T23:08:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/artworks-bianco-balena-pinocchio-40x60-aquatic-creatures-capuzzo-15.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/artworks-bianco-balena-pinocchio-40x60-aquatic-creatures-capuzzo-15.jpg\",\"width\":525,\"height\":684},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"pinocchio white artwork (whales collection)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"230.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1638540455\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"pinocchio white artwork (whales collection) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/","og_locale":"en_US","og_type":"article","og_title":"pinocchio white artwork (whales collection)","og_description":"Subtitle: 40x60 cmAuthor: riccardo capuzzoManufacturer: aquatic creaturesISBN: LDM1638540455","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:08:58+00:00","og_image":[{"width":525,"height":684,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/artworks-bianco-balena-pinocchio-40x60-aquatic-creatures-capuzzo-15.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;230,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/","name":"pinocchio white artwork (whales collection) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/artworks-bianco-balena-pinocchio-40x60-aquatic-creatures-capuzzo-15.jpg","datePublished":"2021-12-03T14:07:36+00:00","dateModified":"2026-05-08T23:08:58+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/artworks-bianco-balena-pinocchio-40x60-aquatic-creatures-capuzzo-15.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/artworks-bianco-balena-pinocchio-40x60-aquatic-creatures-capuzzo-15.jpg","width":525,"height":684},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/pinocchio-white-artwork-whales-collection-riccardo-capuzzo-ldm1638540455\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"pinocchio white artwork (whales collection)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"230.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"LDM1638540455","product_condition":"new"},"df_price":230,"df_sale_price":"","df_regular_price":230,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/artworks-bianco-balena-pinocchio-40x60-aquatic-creatures-capuzzo-15-230x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/54832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=54832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/144229"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=54832"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=54832"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=54832"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=54832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}