{"id":53900,"date":"2021-10-11T11:55:50","date_gmt":"2021-10-11T09:55:50","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/"},"modified":"2026-05-09T01:11:13","modified_gmt":"2026-05-08T23:11:13","slug":"card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/","title":{"rendered":"card &amp; envelope zoodicarta &#8220;red fish&#8221;"},"content":{"rendered":"<p>Card that reproduce an original drawing by <i>Guja Ajolfi<\/i>.<\/p>\n<p><strong>Zoodicarta<\/strong> was born to give life to a universe of drawn animals, often painted, that populate limited edition collections of notebooks, cards, postcards and bookmarks.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>16&#215;11 cm<\/p>\n<p class=\"autore\"><span>Author: <\/span>guja ajolfi<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>Zoodicarta<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1633946149<\/p>\n","protected":false},"featured_media":53898,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2653],"product_tag":[],"class_list":{"0":"post-53900","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-greeting-cards-and-postcards","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>card &amp; envelope zoodicarta &quot;red fish&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"card &amp; envelope zoodicarta &quot;red fish&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 16x11 cmAuthor: guja ajolfiManufacturer: ZoodicartaISBN: LDM1633946149\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:11:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-rettangolare-con-busta-pesce-rosso-ajolfi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"754\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;5,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\\\/\",\"name\":\"card &amp; envelope zoodicarta \\\"red fish\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/biglietto-rettangolare-con-busta-pesce-rosso-ajolfi.jpg\",\"datePublished\":\"2021-10-11T09:55:50+00:00\",\"dateModified\":\"2026-05-08T23:11:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/biglietto-rettangolare-con-busta-pesce-rosso-ajolfi.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/biglietto-rettangolare-con-busta-pesce-rosso-ajolfi.jpg\",\"width\":754,\"height\":532},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"card &amp; envelope zoodicarta &#8220;red fish&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"5.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1633946149\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"card &amp; envelope zoodicarta \"red fish\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/","og_locale":"en_US","og_type":"article","og_title":"card &amp; envelope zoodicarta \"red fish\"","og_description":"Subtitle: 16x11 cmAuthor: guja ajolfiManufacturer: ZoodicartaISBN: LDM1633946149","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:11:13+00:00","og_image":[{"width":754,"height":532,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-rettangolare-con-busta-pesce-rosso-ajolfi.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;5,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/","name":"card &amp; envelope zoodicarta \"red fish\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-rettangolare-con-busta-pesce-rosso-ajolfi.jpg","datePublished":"2021-10-11T09:55:50+00:00","dateModified":"2026-05-08T23:11:13+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-rettangolare-con-busta-pesce-rosso-ajolfi.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-rettangolare-con-busta-pesce-rosso-ajolfi.jpg","width":754,"height":532},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/card-envelope-zoodicarta-red-fish-guja-ajolfi-ldm1633946149\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"card &amp; envelope zoodicarta &#8220;red fish&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"5.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"LDM1633946149","product_condition":"new"},"df_price":5,"df_sale_price":"","df_regular_price":5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/biglietto-rettangolare-con-busta-pesce-rosso-ajolfi-300x212.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/53900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=53900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/53898"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=53900"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=53900"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=53900"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=53900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}