{"id":53181,"date":"2019-02-04T13:13:17","date_gmt":"2019-02-04T12:13:17","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/uncategorized\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/"},"modified":"2026-07-11T04:48:01","modified_gmt":"2026-07-11T02:48:01","slug":"the-idea-factory-a-cura-di-francesco-michienzi-9788890256929","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/","title":{"rendered":"the idea factory"},"content":{"rendered":"<p><strong>What&rsquo;s The Idea Factory? 290 pages, over a thousand images, 28 between designers and design studios that tell the story of contemporary Italian yacht design. An unmissable volume for all those who love boats, the sea and nautical design.<\/strong><\/p>\n<p>The Made in Italy design is equivalent to excellence, luxury and elegance. Its strength is the ability of joining the quality craftsmanship with the innovation, thanks to the genius of Italian entrepreneurs and designers. The aim of &#8220;The Idea Factory&#8221; column is to be a reference point for the global boating industry.<\/p>\n<p>For our publishing company it is very important to convey the values which have made the Italian boat great in the world thanks to the designers of our country who are the key to the success of this important productive sector, through their work they have made an unique heritage which is envied and copied all around the world. They have to be defended and promoted, only with their ideas will Italian boats continue to stand out and be appreciated in all the continents. They are the added value of the Made in Italy.<\/p>\n<p>Languages: English and Italian.<\/p>\n<p>Edition: 2018<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>lo yacht design italiano si racconta<\/p>\n<p class=\"autore\"><span>Author: <\/span>a cura di francesco michienzi<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>international sea press<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788890256929<\/p>\n","protected":false},"featured_media":127587,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2739,3009,2576],"product_tag":[],"class_list":{"0":"post-53181","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-motorboating","7":"product_cat-other-publications-boat-yards-and-designers","8":"product_cat-books-navigation-illustrated-books","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>the idea factory - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"the idea factory\" \/>\n<meta property=\"og:description\" content=\"Subtitle: lo yacht design italiano si raccontaAuthor: a cura di francesco michienziPublisher: international sea pressISBN: 9788890256929\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T02:48:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/ideafactoryloyachtdesignitalianosiracconta-michienzi-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"459\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;80,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\\\/\",\"name\":\"the idea factory - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/ideafactoryloyachtdesignitalianosiracconta-michienzi-3.jpg\",\"datePublished\":\"2019-02-04T12:13:17+00:00\",\"dateModified\":\"2026-07-11T02:48:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/ideafactoryloyachtdesignitalianosiracconta-michienzi-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/ideafactoryloyachtdesignitalianosiracconta-michienzi-3.jpg\",\"width\":459,\"height\":598},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"the idea factory\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"80.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788890256929\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"the idea factory - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/","og_locale":"en_US","og_type":"article","og_title":"the idea factory","og_description":"Subtitle: lo yacht design italiano si raccontaAuthor: a cura di francesco michienziPublisher: international sea pressISBN: 9788890256929","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-11T02:48:01+00:00","og_image":[{"width":459,"height":598,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/ideafactoryloyachtdesignitalianosiracconta-michienzi-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;80,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/","name":"the idea factory - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/ideafactoryloyachtdesignitalianosiracconta-michienzi-3.jpg","datePublished":"2019-02-04T12:13:17+00:00","dateModified":"2026-07-11T02:48:01+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/ideafactoryloyachtdesignitalianosiracconta-michienzi-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/ideafactoryloyachtdesignitalianosiracconta-michienzi-3.jpg","width":459,"height":598},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/the-idea-factory-a-cura-di-francesco-michienzi-9788890256929\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"the idea factory"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"80.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788890256929","product_condition":"new"},"df_price":80,"df_sale_price":"","df_regular_price":80,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/ideafactoryloyachtdesignitalianosiracconta-michienzi-3-230x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/53181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=53181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/127587"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=53181"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=53181"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=53181"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=53181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}