{"id":51389,"date":"2021-05-20T15:34:09","date_gmt":"2021-05-20T13:34:09","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/senza%20categoria\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/"},"modified":"2026-05-09T01:14:48","modified_gmt":"2026-05-08T23:14:48","slug":"bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/","title":{"rendered":"bookmarks &#8220;calli-puzzle&#8221; &#8211; dante alighieri"},"content":{"rendered":"<p style=\"text-align: justify\">The &ldquo;Calli-puzzles&rdquo; are three single bookmarks that, once put together, contain a marine poem: you have to find the right sequence to read it.<\/p>\n<p style=\"text-align: justify\">Handmade on Fabriano Materica paper with nib, sumi ink and gouache.<\/p>\n<p style=\"text-align: justify\">Sizes of a single bookmark: 4.5&times;18 cm.<\/p>\n<p style=\"text-align: justify\">Handicraft.<\/p>\n<p style=\"text-align: justify\">Made in Italy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>callipoem<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>valentina doati<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1621517648<\/p>\n","protected":false},"featured_media":141453,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2655],"product_tag":[],"class_list":{"0":"post-51389","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bookmarks","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>bookmarks &quot;calli-puzzle&quot; - dante alighieri - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"bookmarks &quot;calli-puzzle&quot; - dante alighieri\" \/>\n<meta property=\"og:description\" content=\"Author: callipoemManufacturer: valentina doatiISBN: LDM1621517648\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T23:14:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/segnalibri-calli-puzzle-dante-alighieri-callipoem-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"602\" \/>\n\t<meta property=\"og:image:height\" content=\"747\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\\\/\",\"name\":\"bookmarks \\\"calli-puzzle\\\" - dante alighieri - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/segnalibri-calli-puzzle-dante-alighieri-callipoem-1.jpg\",\"datePublished\":\"2021-05-20T13:34:09+00:00\",\"dateModified\":\"2026-05-08T23:14:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/segnalibri-calli-puzzle-dante-alighieri-callipoem-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/segnalibri-calli-puzzle-dante-alighieri-callipoem-1.jpg\",\"width\":602,\"height\":747},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"bookmarks &#8220;calli-puzzle&#8221; &#8211; dante alighieri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1621517648\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"bookmarks \"calli-puzzle\" - dante alighieri - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/","og_locale":"en_US","og_type":"article","og_title":"bookmarks \"calli-puzzle\" - dante alighieri","og_description":"Author: callipoemManufacturer: valentina doatiISBN: LDM1621517648","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T23:14:48+00:00","og_image":[{"width":602,"height":747,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/segnalibri-calli-puzzle-dante-alighieri-callipoem-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/","name":"bookmarks \"calli-puzzle\" - dante alighieri - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/segnalibri-calli-puzzle-dante-alighieri-callipoem-1.jpg","datePublished":"2021-05-20T13:34:09+00:00","dateModified":"2026-05-08T23:14:48+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/segnalibri-calli-puzzle-dante-alighieri-callipoem-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/segnalibri-calli-puzzle-dante-alighieri-callipoem-1.jpg","width":602,"height":747},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/bookmarks-calli-puzzle-dante-alighieri-callipoem-ldm1621517648\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"bookmarks &#8220;calli-puzzle&#8221; &#8211; dante alighieri"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"LDM1621517648","product_condition":"new"},"df_price":14,"df_sale_price":"","df_regular_price":14,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/segnalibri-calli-puzzle-dante-alighieri-callipoem-1-242x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/51389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=51389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/141453"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=51389"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=51389"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=51389"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=51389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}