{"id":165516,"date":"2026-04-23T14:56:44","date_gmt":"2026-04-23T12:56:44","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/"},"modified":"2026-07-11T00:05:20","modified_gmt":"2026-07-10T22:05:20","slug":"isole-meravigliose-nicola-balossi-restelli-9788854061668","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/","title":{"rendered":"Isole meravigliose"},"content":{"rendered":"<p>Meta di fuga e vacanze per eccellenza, l&#8217;isola &egrave; insieme <strong>privilegio e suggestione<\/strong>, oltre che <strong>luogo simbolico in cui si resta soli con s&eacute; stessi<\/strong>. Non solo tropici. mari corallini o silenziosi paesaggi del nord, ma anche tesori nascosti, avventure, viaggi mistici.<\/p>\n<p><strong>Protette dall&#8217;acqua<\/strong> e <strong>spesso disabitate o inaccessibili<\/strong>, oppure <strong>mete paradisiache<\/strong> ambite da viaggiatori e turisti provenienti da ogni parte del mondo, ciascuna isola possiede un volto, una personalit&agrave;, una storia da raccontare.<\/p>\n<p>Alcune di queste sono state selezionate e raccontate in <strong>una serie di ritratti<\/strong>, in cui le parole si intrecciano con meravigliose e suggestive fotografie.<\/p>\n<p><em>Kauai &#8211; Bora Bora &#8211; Isola di Pasqua &#8211; Galapagos &#8211; Eleuthera &#8211; Los Roques &#8211; Fernando De Noronha &#8211; Corvo &#8211; Lanzarote &#8211; Mont Saint-Michel &#8211; Lofoten &#8211; Capri &#8211; Itaca &#8211; Aldabra &#8211; Sainte-Marie &#8211; Rpdrigues &#8211; Maldive &#8211; Christmas Island &#8211; Bali &#8211; Palawan &#8211; Okinawa &#8211; Eil Malk &#8211; Whitsunday &#8211; Viti Levu<\/em><\/p>\n<p>Edizione: 2026<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>Avventure, storie e leggende tra i paradisi naturali del pianeta<\/p>\n<p class=\"autore\"><span>Author: <\/span>Nicola Balossi Restelli<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>edizioni white star<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788854061668<\/p>\n","protected":false},"featured_media":165506,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2646],"product_tag":[],"class_list":{"0":"post-165516","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-world-picture-books-tourism","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Isole meravigliose - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isole meravigliose\" \/>\n<meta property=\"og:description\" content=\"Subtitle: Avventure, storie e leggende tra i paradisi naturali del pianetaAuthor: Nicola Balossi RestelliPublisher: edizioni white starISBN: 9788854061668\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:05:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-meravigliose-balossi-restelli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;24,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-meravigliose-nicola-balossi-restelli-9788854061668\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-meravigliose-nicola-balossi-restelli-9788854061668\\\/\",\"name\":\"Isole meravigliose - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-meravigliose-nicola-balossi-restelli-9788854061668\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-meravigliose-nicola-balossi-restelli-9788854061668\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isole-meravigliose-balossi-restelli.jpg\",\"datePublished\":\"2026-04-23T12:56:44+00:00\",\"dateModified\":\"2026-07-10T22:05:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-meravigliose-nicola-balossi-restelli-9788854061668\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-meravigliose-nicola-balossi-restelli-9788854061668\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-meravigliose-nicola-balossi-restelli-9788854061668\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isole-meravigliose-balossi-restelli.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/isole-meravigliose-balossi-restelli.jpg\",\"width\":500,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/isole-meravigliose-nicola-balossi-restelli-9788854061668\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Isole meravigliose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"24.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788854061668\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Isole meravigliose - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/","og_locale":"en_US","og_type":"article","og_title":"Isole meravigliose","og_description":"Subtitle: Avventure, storie e leggende tra i paradisi naturali del pianetaAuthor: Nicola Balossi RestelliPublisher: edizioni white starISBN: 9788854061668","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:05:20+00:00","og_image":[{"width":500,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-meravigliose-balossi-restelli.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;24,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/","name":"Isole meravigliose - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-meravigliose-balossi-restelli.jpg","datePublished":"2026-04-23T12:56:44+00:00","dateModified":"2026-07-10T22:05:20+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-meravigliose-balossi-restelli.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-meravigliose-balossi-restelli.jpg","width":500,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/isole-meravigliose-nicola-balossi-restelli-9788854061668\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Isole meravigliose"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"24.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788854061668","product_condition":"new"},"df_price":24.9,"df_sale_price":"","df_regular_price":24.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/isole-meravigliose-balossi-restelli-214x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/165516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=165516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/165506"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=165516"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=165516"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=165516"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=165516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}