{"id":164969,"date":"2026-04-16T17:41:21","date_gmt":"2026-04-16T15:41:21","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/"},"modified":"2026-05-09T00:00:46","modified_gmt":"2026-05-08T22:00:46","slug":"silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/","title":{"rendered":"Silvia Spider e il mistero in alto mare"},"content":{"rendered":"<p>Un&#8217;indagine in crociera per la Spider Investigation!<\/p>\n<p><strong>Silvia Spider non riesce a dormir<\/strong>e. Tra poche ore, con la sua classe e con l&#8217;amica del cuore Sofia la Bionda, <strong>si imbarcher&agrave; sulla Nave dei Libri<\/strong>, diretta a <em>Barcellona <\/em>per la Giornata Internazionale del Libro.<\/p>\n<p>Le due ragazzine non vedono l&#8217;ora di percorrere le strade della citt&agrave; in festa, traboccanti di rose rosse, bandiere e bancarelle di libri.<\/p>\n<p>Ma <strong>il viaggio si rivela meno piacevole del previsto<\/strong>: la Spider Investigation, al completo con i fidati amici L&eacute;on e Massimiliano, scoprir&agrave; che <strong>sulla nave c&#8217;&egrave; un criminale<\/strong>, e tentando di sventare i suoi loschi affari i quattro ragazzi si troveranno alle prese con una storia ben pi&ugrave; grande di loro.<\/p>\n<p>Et&agrave;: <strong>11+<\/strong><\/p>\n<p>Edizione: 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>Gabriella Genisi &#8211; Antonio Laudati<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Il Battello a Vapore (Piemme)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791223850176<\/p>\n","protected":false},"featured_media":164967,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2610,2613],"product_tag":[],"class_list":{"0":"post-164969","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-12-anni-children-and-young-adults","7":"product_cat-9-12-years","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Silvia Spider e il mistero in alto mare - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Silvia Spider e il mistero in alto mare\" \/>\n<meta property=\"og:description\" content=\"Author: Gabriella Genisi - Antonio LaudatiPublisher: Il Battello a Vapore (Piemme)ISBN: 9791223850176\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:00:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/silvia-spider-e-il-mistero-in-alto-mare-genisi-laudati.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"757\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;12,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\\\/\",\"name\":\"Silvia Spider e il mistero in alto mare - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/silvia-spider-e-il-mistero-in-alto-mare-genisi-laudati.jpg\",\"datePublished\":\"2026-04-16T15:41:21+00:00\",\"dateModified\":\"2026-05-08T22:00:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/silvia-spider-e-il-mistero-in-alto-mare-genisi-laudati.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/silvia-spider-e-il-mistero-in-alto-mare-genisi-laudati.jpg\",\"width\":500,\"height\":757},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Silvia Spider e il mistero in alto mare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"12.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791223850176\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Silvia Spider e il mistero in alto mare - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/","og_locale":"en_US","og_type":"article","og_title":"Silvia Spider e il mistero in alto mare","og_description":"Author: Gabriella Genisi - Antonio LaudatiPublisher: Il Battello a Vapore (Piemme)ISBN: 9791223850176","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:00:46+00:00","og_image":[{"width":500,"height":757,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/silvia-spider-e-il-mistero-in-alto-mare-genisi-laudati.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;12,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/","name":"Silvia Spider e il mistero in alto mare - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/silvia-spider-e-il-mistero-in-alto-mare-genisi-laudati.jpg","datePublished":"2026-04-16T15:41:21+00:00","dateModified":"2026-05-08T22:00:46+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/silvia-spider-e-il-mistero-in-alto-mare-genisi-laudati.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/silvia-spider-e-il-mistero-in-alto-mare-genisi-laudati.jpg","width":500,"height":757},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/silvia-spider-e-il-mistero-in-alto-mare-gabriella-genisi-antonio-laudati-9791223850176\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Silvia Spider e il mistero in alto mare"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"12.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9791223850176","product_condition":"new"},"df_price":12.9,"df_sale_price":"","df_regular_price":12.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/silvia-spider-e-il-mistero-in-alto-mare-genisi-laudati-198x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/164969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=164969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/164967"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=164969"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=164969"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=164969"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=164969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}