{"id":164959,"date":"2026-04-16T17:27:58","date_gmt":"2026-04-16T15:27:58","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/"},"modified":"2026-05-09T00:00:46","modified_gmt":"2026-05-08T22:00:46","slug":"capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/","title":{"rendered":"Capitan Lupita &#8211; Il ciondolo magico"},"content":{"rendered":"<p>Nell&#8217;<strong>Arcipelago delle Isole Perdute<\/strong> arriva la ciurma pi&ugrave; famosa di tutte: sono <strong>le ragazze del Galeone Volante<\/strong>, piratesse senza timori, veloci come falchi e agguerrite come tigri!<\/p>\n<p>Guai in vista per Danielle! Dal passato <strong>ritorna il contadino<\/strong> che l&#8217;aveva ritrovata senza memoria sulla spiaggia e <strong>le chiede il ciondolo<\/strong> che porta al collo! Ma chi c&#8217;&egrave; dietro questa richiesta? Tutto fa pensare a&#8230; The Duke, il pirata in grado di ingannare chiunque!<\/p>\n<p>Et&agrave;: <strong>6+<\/strong><\/p>\n<p>Edizione: 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>Tea Stilton<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Piemme Tea Stilton (Ragazzi Mondadori)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791223851791<\/p>\n","protected":false},"featured_media":164957,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2617],"product_tag":[],"class_list":{"0":"post-164959","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-illustrated-books-and-fiction-6-9-years","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Capitan Lupita - Il ciondolo magico - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capitan Lupita - Il ciondolo magico\" \/>\n<meta property=\"og:description\" content=\"Author: Tea StiltonPublisher: Piemme Tea Stilton (Ragazzi Mondadori)ISBN: 9791223851791\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:00:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-lupita-il-ciondolo-magico-tea-stilton.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"721\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\\\/\",\"name\":\"Capitan Lupita - Il ciondolo magico - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/capitan-lupita-il-ciondolo-magico-tea-stilton.jpg\",\"datePublished\":\"2026-04-16T15:27:58+00:00\",\"dateModified\":\"2026-05-08T22:00:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/capitan-lupita-il-ciondolo-magico-tea-stilton.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/capitan-lupita-il-ciondolo-magico-tea-stilton.jpg\",\"width\":500,\"height\":721},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Capitan Lupita &#8211; Il ciondolo magico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791223851791\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Capitan Lupita - Il ciondolo magico - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/","og_locale":"en_US","og_type":"article","og_title":"Capitan Lupita - Il ciondolo magico","og_description":"Author: Tea StiltonPublisher: Piemme Tea Stilton (Ragazzi Mondadori)ISBN: 9791223851791","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:00:46+00:00","og_image":[{"width":500,"height":721,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-lupita-il-ciondolo-magico-tea-stilton.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,50","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/","name":"Capitan Lupita - Il ciondolo magico - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-lupita-il-ciondolo-magico-tea-stilton.jpg","datePublished":"2026-04-16T15:27:58+00:00","dateModified":"2026-05-08T22:00:46+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-lupita-il-ciondolo-magico-tea-stilton.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-lupita-il-ciondolo-magico-tea-stilton.jpg","width":500,"height":721},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/capitan-lupita-il-ciondolo-magico-tea-stilton-9791223851791\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Capitan Lupita &#8211; Il ciondolo magico"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.50","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9791223851791","product_condition":"new"},"df_price":14.5,"df_sale_price":"","df_regular_price":14.5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/capitan-lupita-il-ciondolo-magico-tea-stilton-208x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/164959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=164959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/164957"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=164959"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=164959"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=164959"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=164959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}