{"id":163734,"date":"2026-03-28T16:27:14","date_gmt":"2026-03-28T15:27:14","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/gallura-e-la-maddalena-aa-vv-9788836584468\/"},"modified":"2026-05-09T00:01:35","modified_gmt":"2026-05-08T22:01:35","slug":"gallura-e-la-maddalena-aa-vv-9788836584468","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/","title":{"rendered":"Gallura e La Maddalena"},"content":{"rendered":"<p><strong>Calette e insenature, fiordi e scogliere, fondali<\/strong> scrigno di biodiversit&agrave;, e poi un <strong>entroterra<\/strong> che conserva gelosamente le tracce di civilt&agrave; antichissime. Su tutto, le trasparenze di un mare gradito anche a <strong>balenottere e tursiopi<\/strong>.<\/p>\n<p>In questa guida vi raccontano:<\/p>\n<ul>\n<li>trekking sulle mulattiere, gite in kayak e in barca a vela, passeggiate archeologiche&#8230; tutte le occasioni per una vacanza attiva<\/li>\n<li>immersioni e snorkeling nelle Aree Marine Protette di Tavolara e della Maddalena<\/li>\n<li>racconti, storie, canti di <em>Gallura<\/em>, gli indirizzi consigliati per soste golose e per lo shopping<\/li>\n<\/ul>\n<p>Nella <strong>mappa allegata<\/strong> il territorio del Parco Nazionale dell&#8217;<em>Arcipelago della Maddalena<\/em>, sentieri, spiagge, stazzi.<\/p>\n<p>Edizione: 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>Spiagge, isole, nuraghi: i paesaggi di una terra modellata nel granito<\/p>\n<p class=\"autore\"><span>Author: <\/span>AA.VV.<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Touring Club Italiano (TCI)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788836584468<\/p>\n","protected":false},"featured_media":163732,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2640],"product_tag":[],"class_list":{"0":"post-163734","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sardinia-italy-tourist-guides","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gallura e La Maddalena - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gallura e La Maddalena\" \/>\n<meta property=\"og:description\" content=\"Subtitle: Spiagge, isole, nuraghi: i paesaggi di una terra modellata nel granitoAuthor: AA.VV.Publisher: Touring Club Italiano (TCI)ISBN: 9788836584468\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:01:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gallura-e-la-maddalena-tci.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"747\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;14,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gallura-e-la-maddalena-aa-vv-9788836584468\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gallura-e-la-maddalena-aa-vv-9788836584468\\\/\",\"name\":\"Gallura e La Maddalena - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gallura-e-la-maddalena-aa-vv-9788836584468\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gallura-e-la-maddalena-aa-vv-9788836584468\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/gallura-e-la-maddalena-tci.jpg\",\"datePublished\":\"2026-03-28T15:27:14+00:00\",\"dateModified\":\"2026-05-08T22:01:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gallura-e-la-maddalena-aa-vv-9788836584468\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gallura-e-la-maddalena-aa-vv-9788836584468\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gallura-e-la-maddalena-aa-vv-9788836584468\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/gallura-e-la-maddalena-tci.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/gallura-e-la-maddalena-tci.jpg\",\"width\":500,\"height\":747},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/gallura-e-la-maddalena-aa-vv-9788836584468\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gallura e La Maddalena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"14.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788836584468\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gallura e La Maddalena - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/","og_locale":"en_US","og_type":"article","og_title":"Gallura e La Maddalena","og_description":"Subtitle: Spiagge, isole, nuraghi: i paesaggi di una terra modellata nel granitoAuthor: AA.VV.Publisher: Touring Club Italiano (TCI)ISBN: 9788836584468","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:01:35+00:00","og_image":[{"width":500,"height":747,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gallura-e-la-maddalena-tci.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;14,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/","name":"Gallura e La Maddalena - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gallura-e-la-maddalena-tci.jpg","datePublished":"2026-03-28T15:27:14+00:00","dateModified":"2026-05-08T22:01:35+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gallura-e-la-maddalena-tci.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gallura-e-la-maddalena-tci.jpg","width":500,"height":747},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/gallura-e-la-maddalena-aa-vv-9788836584468\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Gallura e La Maddalena"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"14.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788836584468","product_condition":"new"},"df_price":14.9,"df_sale_price":"","df_regular_price":14.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/gallura-e-la-maddalena-tci-201x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/163734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=163734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/163732"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=163734"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=163734"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=163734"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=163734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}