{"id":161321,"date":"2026-02-07T15:25:46","date_gmt":"2026-02-07T14:25:46","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/storia-delle-stelle-adam-smith-9791255962847\/"},"modified":"2026-07-11T00:09:19","modified_gmt":"2026-07-10T22:09:19","slug":"storia-delle-stelle-adam-smith-9791255962847","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/","title":{"rendered":"Storia delle stelle"},"content":{"rendered":"<p><em>&ldquo;La meraviglia, pertanto, e non l&rsquo;aspettativa di ottenere vantaggi grazie alle sue scoperte, &egrave; il primo principio che spinge l&rsquo;umanit&agrave; allo studio della Filosofia, la scienza che pretende di svelare i legami nascosti che uniscono le varie apparizioni della natura; e l&rsquo;umanit&agrave; persegue questo studio per s&eacute; stessa, come piacere o bene originario, senza prendere in considerazione la sua tendenza a procurarle gli strumenti per ottenere altri piaceri.&rdquo;<\/em><br \/><em>&nbsp;<\/em><br \/>&nbsp;<br \/>C&rsquo;&egrave; una forza che attraversa i secoli e i cieli: &egrave; <strong>la meraviglia, sentimento suscitato da ci&ograve; che &egrave; nuovo, insolito e straordinario<\/strong>, e che &egrave; il <strong>propulsore della conoscenza umana<\/strong>. Questa l&rsquo;idea al fondo della <em>Storia delle stelle<\/em> (<em>History of Astronomy<\/em>), che <em>Adam Smith<\/em>, poco pi&ugrave; che ventenne, inizi&ograve; a comporre nel <strong>1744<\/strong> e che vide la luce solo pi&ugrave; di mezzo secolo pi&ugrave; tardi e dopo la scomparsa del filosofo scozzese, grazie agli amici che curarono l&rsquo;edizione delle sue carte inedite. La forma apparente di trattato astronomico non deve ingannare: in queste pagine, dense e limpide, <strong><em>Smith <\/em>osserva i movimenti del firmamento, leggendovi di riflesso la storia di come gli esseri umani cerchino irriducibilmente di placare la loro sete di conoscenza<\/strong>.<\/p>\n<p>La storia dell&rsquo;osservazione degli astri, cos&igrave;, diventa nella <em>Storia delle stelle<\/em> un <strong>piccolo trattato sull&rsquo;intelletto umano, sulle paure e le aspirazioni<\/strong> della nostra specie, e sulla ricerca d&rsquo;ordine e di bellezza che guida ogni nostra scoperta. <em>La Storia delle stelle<\/em>, nelle cui pagine troviamo il primo accenno di <em>Smith <\/em>alla mano invisibile, rivela un lato poetico e speculativo che pochi conoscono del futuro fondatore della economia politica classica.<\/p>\n<p>Sono pagine, queste, in cui gi&agrave; <strong>si avverte il respiro lungo dell&rsquo;illuminismo<\/strong>, la <strong>tensione metafisica di chi scruta il cielo non per misurarlo, ma per abitarlo col pensiero<\/strong>. Sono pagine, queste, capaci ancora di restituire a lettrici e lettori contemporanei il bagliore delle stelle che quasi tre secoli fa le hanno ispirate.<\/p>\n<p>Edizione: 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>Adam Smith<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Pola &#8211; Luiss University Press<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791255962847<\/p>\n","protected":false},"featured_media":166790,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2579,2977,2983],"product_tag":[],"class_list":{"0":"post-161321","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-celestial-and-traditional-navigation-and-astronomy","7":"product_cat-environment-and-ecology","8":"product_cat-literary-essays","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Storia delle stelle - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Storia delle stelle\" \/>\n<meta property=\"og:description\" content=\"Author: Adam SmithPublisher: Pola - Luiss University PressISBN: 9791255962847\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:09:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storia-delle-stelle-smith-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;22,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-delle-stelle-adam-smith-9791255962847\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-delle-stelle-adam-smith-9791255962847\\\/\",\"name\":\"Storia delle stelle - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-delle-stelle-adam-smith-9791255962847\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-delle-stelle-adam-smith-9791255962847\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/storia-delle-stelle-smith-3.jpg\",\"datePublished\":\"2026-02-07T14:25:46+00:00\",\"dateModified\":\"2026-07-10T22:09:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-delle-stelle-adam-smith-9791255962847\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-delle-stelle-adam-smith-9791255962847\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-delle-stelle-adam-smith-9791255962847\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/storia-delle-stelle-smith-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/storia-delle-stelle-smith-3.jpg\",\"width\":500,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/storia-delle-stelle-adam-smith-9791255962847\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Storia delle stelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"22.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791255962847\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Storia delle stelle - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/","og_locale":"en_US","og_type":"article","og_title":"Storia delle stelle","og_description":"Author: Adam SmithPublisher: Pola - Luiss University PressISBN: 9791255962847","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:09:19+00:00","og_image":[{"width":500,"height":768,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storia-delle-stelle-smith-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;22,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/","name":"Storia delle stelle - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storia-delle-stelle-smith-3.jpg","datePublished":"2026-02-07T14:25:46+00:00","dateModified":"2026-07-10T22:09:19+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storia-delle-stelle-smith-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storia-delle-stelle-smith-3.jpg","width":500,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/storia-delle-stelle-adam-smith-9791255962847\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Storia delle stelle"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"22.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9791255962847","product_condition":"new"},"df_price":22,"df_sale_price":"","df_regular_price":22,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/storia-delle-stelle-smith-3-195x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/161321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=161321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/166790"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=161321"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=161321"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=161321"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=161321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}