{"id":154451,"date":"2025-09-12T17:12:30","date_gmt":"2025-09-12T15:12:30","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/"},"modified":"2026-05-09T00:08:12","modified_gmt":"2026-05-08T22:08:12","slug":"peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/","title":{"rendered":"Peloponneso (Tascabili per viaggiare)"},"content":{"rendered":"<p><strong>La penisola del Peloponneso<\/strong> racchiude in s&egrave; un&rsquo;intera nazione, o meglio ancora, custodisce i ricordi e le tradizioni della nascita della civilt&agrave; occidentale come la conosciamo oggi. <strong>Le citt&agrave; e i resti <\/strong>che si possono trovare in questa piccola parte di Grecia risuonano come nomi familiari nelle orecchie di tutti: la temuta <strong>Sparta<\/strong>, patria di Leonida e di guerrieri sempre pronti a combattere per proteggere il loro popolo, <strong>Corinto<\/strong>, dove Giasone, il capo degli Argonauti, giunse con Medea, dopo i suoi viaggi, il sito archeologico di <strong>Olimpia<\/strong>, dove la fiamma dei Giochi Olimpici &egrave; stata accesa e arde ancora. Se <strong>la storia e la mitologia<\/strong> sono il vostro pane, allora non perdetevi l&rsquo;occasione di visitare questi luoghi.<\/p>\n<p>Ma il Peloponneso non &egrave; solo antichit&agrave; e divinit&agrave; arroganti e sempre in combutta fra di loro: <strong>Kalamata e Messinia<\/strong>, la terra delle olive, sono le protagoniste di un territorio da scoprire, con strade mozzafiato e villaggi ospitali e caratteristici. <strong>Nafplio<\/strong>, prima capitale della Grecia, &egrave; anche una piccola metropoli, dove si pu&ograve; trovare dello svago e del divertimento di alto livello. E che ne dite invece di rilassarvi al mare: qui <strong>le spiagge di sabbia fine <\/strong>paiono infinite e illimitate, intervallate da <strong>grotte magiche e isolette idilliache<\/strong>, dove si pu&ograve; prendere il sole, fare un bagno o ammirare il tramonto o il chiaro di luna. E in aggiunta, ecco che da questa penisola diventata isola per il <strong>Canale di Corinto<\/strong>, si possono raggiungere numerose altre isole che, anche se non sono sotto la giurisdizione di questo territorio, sono facilmente visitabili dai porti di questa zona.<\/p>\n<p>Allora,<strong> zaino<\/strong> in spalla, <strong>guida<\/strong> alla mano, <strong>taccuino <\/strong>per prendere appunti e un bel <strong>costume <\/strong>da bagno: il Peloponneso vi aspetta!<\/p>\n<p><strong>Libro con mappa pieghevole staccabile.<\/strong><\/p>\n<p>Edizione: 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>Elisabeth Heinze<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Dumont (Guido Tommasi Editore)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788899694852<\/p>\n","protected":false},"featured_media":163834,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3104],"product_tag":[],"class_list":{"0":"post-154451","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-croatia-slovenia-montenegro-albania-greece-and-turkey","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Peloponneso (Tascabili per viaggiare) - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peloponneso (Tascabili per viaggiare)\" \/>\n<meta property=\"og:description\" content=\"Author: Elisabeth HeinzePublisher: Dumont (Guido Tommasi Editore)ISBN: 9788899694852\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:08:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-dumont-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"784\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\\\/\",\"name\":\"Peloponneso (Tascabili per viaggiare) - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-dumont-3.jpg\",\"datePublished\":\"2025-09-12T15:12:30+00:00\",\"dateModified\":\"2026-05-08T22:08:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-dumont-3.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-dumont-3.jpg\",\"width\":500,\"height\":784},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Peloponneso (Tascabili per viaggiare)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788899694852\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Peloponneso (Tascabili per viaggiare) - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/","og_locale":"en_US","og_type":"article","og_title":"Peloponneso (Tascabili per viaggiare)","og_description":"Author: Elisabeth HeinzePublisher: Dumont (Guido Tommasi Editore)ISBN: 9788899694852","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:08:12+00:00","og_image":[{"width":500,"height":784,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-dumont-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,90","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/","name":"Peloponneso (Tascabili per viaggiare) - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-dumont-3.jpg","datePublished":"2025-09-12T15:12:30+00:00","dateModified":"2026-05-08T22:08:12+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-dumont-3.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-dumont-3.jpg","width":500,"height":784},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-9788899694852\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Peloponneso (Tascabili per viaggiare)"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788899694852","product_condition":"new"},"df_price":19.9,"df_sale_price":"","df_regular_price":19.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/peloponneso-tascabili-per-viaggiare-elisabeth-heinze-dumont-3-191x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/154451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=154451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/163834"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=154451"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=154451"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=154451"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=154451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}