{"id":153976,"date":"2025-08-21T17:04:38","date_gmt":"2025-08-21T15:04:38","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/"},"modified":"2026-07-11T00:16:57","modified_gmt":"2026-07-10T22:16:57","slug":"la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/","title":{"rendered":"la politica navale del conte di cavour"},"content":{"rendered":"<p><strong>Raro esemplare intonso della prima edizione dell&rsquo;Editrice Nuova Borsa del 1932 (Anno X dell&rsquo;Era Fascista) in buono stato di conservazione. In-8, brossura stampata in rosso e nero con bollo numerato al dorso, segni d&#8217;usura e fortemente ingiallita; 144 pp. ingiallite e con qualche fioritura, alcune con pieghe; con dedica a penna dell&#8217;autore ed ex-libris dell&#8217;Ammiraglio Filippo Camperio a pagina 1 ed errata corrige coeva su foglio sciolto.<\/strong><\/p>\n<p>Dalla prefazione dell&#8217;autore: <em>[&#8230;] Mi &egrave; parso interessante in un momento di fervidi studi storici e di ardite iniziative sul mare riunire insieme e porre in luce i diversi momenti della politica di Cavour che hanno relazioni con le attivit&agrave; navali del Risorgimento, delle quali il Conte fu l&#8217;animatore e l&#8217;ispiratore supremo. E questo studio breve, scritto da un marinaio che non ha pretesa di lettere, vuole servire sopratutto per la maggior conoscenza di quei marinai che al mare hanno dedicato, oltre alle energie fisiche, quelle morali e intellettuali. Ch&egrave; il mare, oltre ad essere il pi&ugrave; vasto campo dei traffici, &egrave;, per i migliori, palestra di attivit&agrave; spirituale che pu&ograve; valere, da sola, a riempire tutta una vita. [&#8230;]<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>mario battaglieri<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>editrice nuova borsa<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1755788677<\/p>\n","protected":false},"featured_media":153974,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3044,3022],"product_tag":[],"class_list":{"0":"post-153976","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-essays-modern-era","7":"product_cat-other-studies","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>la politica navale del conte di cavour - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"la politica navale del conte di cavour\" \/>\n<meta property=\"og:description\" content=\"Author: mario battaglieriPublisher: editrice nuova borsaISBN: LDM1755788677\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:16:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-editrice-nuova-borsa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"799\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;30,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\\\/\",\"name\":\"la politica navale del conte di cavour - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-editrice-nuova-borsa.jpg\",\"datePublished\":\"2025-08-21T15:04:38+00:00\",\"dateModified\":\"2026-07-10T22:16:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-editrice-nuova-borsa.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-editrice-nuova-borsa.jpg\",\"width\":500,\"height\":799},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"la politica navale del conte di cavour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"30.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1755788677\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"la politica navale del conte di cavour - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/","og_locale":"en_US","og_type":"article","og_title":"la politica navale del conte di cavour","og_description":"Author: mario battaglieriPublisher: editrice nuova borsaISBN: LDM1755788677","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:16:57+00:00","og_image":[{"width":500,"height":799,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-editrice-nuova-borsa.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;30,00","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/","name":"la politica navale del conte di cavour - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-editrice-nuova-borsa.jpg","datePublished":"2025-08-21T15:04:38+00:00","dateModified":"2026-07-10T22:16:57+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-editrice-nuova-borsa.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-editrice-nuova-borsa.jpg","width":500,"height":799},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-ldm1755788677\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"la politica navale del conte di cavour"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"30.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"LDM1755788677","product_condition":"new"},"df_price":30,"df_sale_price":"","df_regular_price":30,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/la-politica-navale-del-conte-di-cavour-mario-battaglieri-editrice-nuova-borsa-188x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/153976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=153976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/153974"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=153976"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=153976"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=153976"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=153976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}