{"id":153957,"date":"2025-08-21T15:12:16","date_gmt":"2025-08-21T13:12:16","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/"},"modified":"2026-05-09T00:08:41","modified_gmt":"2026-05-08T22:08:41","slug":"a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/","title":{"rendered":"a sud di sant&#8217;elena"},"content":{"rendered":"<p>Luglio 1892. Il brigantino <em>Italia<\/em> parte da Swansea, nel Galles, con un carico di antracite. L&rsquo;equipaggio &egrave; composto in massima parte da liguri, fra cui tre giovani di Camogli. C&rsquo;&egrave; anche Jim, un ragazzo clandestino che sulla nave ha trovato rifugio, fuggendo da una vita di miseria e soprusi. Giunti, per&ograve;, nel mezzo dell&rsquo;Atlantico, a bordo della nave scoppia un incendio, a causa dell&rsquo;autocombustione del carbon fossile, mentre poco dopo una terribile tempesta porta via l&rsquo;albero di maestra.<\/p>\n<p>In una situazione cos&igrave; drammatica, con la velatura ridotta e le fiamme che minacciano di far esplodere l&rsquo;imbarcazione, il capitano pu&ograve; solo tentare di portare il brigantino a naufragare sulla terraferma pi&ugrave; vicina: la minuscola isola di Tristan da Cunha.<\/p>\n<p>L&igrave; i superstiti verranno accolti dalla piccola comunit&agrave; di residenti, con i quali si instaurer&agrave; un rapporto di comunanza che cambier&agrave; per sempre i destini di entrambi.<\/p>\n<p>Edizione: 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>giuseppina m. picetti<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>Libreria Editrice Ultima Spiaggia (Nutrimenti)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9788898607594<\/p>\n","protected":false},"featured_media":153959,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2809],"product_tag":[],"class_list":{"0":"post-153957","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-novels","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>a sud di sant&#039;elena - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"a sud di sant&#039;elena\" \/>\n<meta property=\"og:description\" content=\"Author: giuseppina m. picettiPublisher: Libreria Editrice Ultima Spiaggia (Nutrimenti)ISBN: 9788898607594\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:08:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/a-sud-di-sant-elena-giuseppina-m-picetti-ultima-spiaggia-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"781\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;19,50\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\\\/\",\"name\":\"a sud di sant'elena - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/a-sud-di-sant-elena-giuseppina-m-picetti-ultima-spiaggia-1.jpg\",\"datePublished\":\"2025-08-21T13:12:16+00:00\",\"dateModified\":\"2026-05-08T22:08:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/a-sud-di-sant-elena-giuseppina-m-picetti-ultima-spiaggia-1.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/a-sud-di-sant-elena-giuseppina-m-picetti-ultima-spiaggia-1.jpg\",\"width\":500,\"height\":781},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"a sud di sant&#8217;elena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"19.50\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9788898607594\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"a sud di sant'elena - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/","og_locale":"en_US","og_type":"article","og_title":"a sud di sant'elena","og_description":"Author: giuseppina m. picettiPublisher: Libreria Editrice Ultima Spiaggia (Nutrimenti)ISBN: 9788898607594","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:08:41+00:00","og_image":[{"width":500,"height":781,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/a-sud-di-sant-elena-giuseppina-m-picetti-ultima-spiaggia-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;19,50","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/","name":"a sud di sant'elena - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/a-sud-di-sant-elena-giuseppina-m-picetti-ultima-spiaggia-1.jpg","datePublished":"2025-08-21T13:12:16+00:00","dateModified":"2026-05-08T22:08:41+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/a-sud-di-sant-elena-giuseppina-m-picetti-ultima-spiaggia-1.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/a-sud-di-sant-elena-giuseppina-m-picetti-ultima-spiaggia-1.jpg","width":500,"height":781},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/a-sud-di-sant-elena-giuseppina-m-picetti-9788898607594\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"a sud di sant&#8217;elena"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"19.50","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"9788898607594","product_condition":"new"},"df_price":19.5,"df_sale_price":"","df_regular_price":19.5,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/a-sud-di-sant-elena-giuseppina-m-picetti-ultima-spiaggia-1-192x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/153957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=153957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/153959"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=153957"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=153957"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=153957"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=153957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}