{"id":153695,"date":"2025-08-05T18:29:24","date_gmt":"2025-08-05T16:29:24","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/"},"modified":"2026-07-11T00:17:04","modified_gmt":"2026-07-10T22:17:04","slug":"manuale-di-navigazione-giorgio-sorrentino-ldm1754411362","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/","title":{"rendered":"manuale di navigazione"},"content":{"rendered":"<p><strong>Raro esemplare della prima edizione dello Stabilimento Tipografico E. Pietrocola del 1893 in ottimo stato di conservazione. In-8, legatura editoriale con copertina rigida telata marrone (con evidenti segni del tempo e bollo numerato al dorso); 136 pp. appena ingiallite, con risguardi illustrati con motivi floreali in nero e firma dell&rsquo;Ammiraglio Filippo Camperio a pag. 1 e al frontespizio; con numerose tabelle e illustrazioni in nero nel testo e calcoli a matita a pag. 124 e 128.<\/strong><\/p>\n<p>Dalla nota introduttiva dell&#8217;autore:&nbsp;<em>Questo&nbsp;<\/em>Manuale di Navigazione<em>, pubblicato col permesso del Ministero della Marina, riassume la parte pratica delle mie lezioni di Astronomia Nautica, che dettai nella R. Accademia Navale di Livorno.<\/em><\/p>\n<p><em>Esso potr&agrave; servire di guida ai giovani Ufficiali, chiamati alla direzione della rotta della nave.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>per determinare le coordinate geografiche della nave con rette d&#8217;altezza<\/p>\n<p class=\"autore\"><span>Author: <\/span>giorgio sorrentino<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>stabilimento tipografico e. pietrocola<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1754411362<\/p>\n","protected":false},"featured_media":158280,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2579,2606,2989],"product_tag":[],"class_list":{"0":"post-153695","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-books-celestial-and-traditional-navigation-and-astronomy","7":"product_cat-encyclopedias-atlases-and-handbooks","8":"product_cat-professional-titles","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>manuale di navigazione - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"manuale di navigazione\" \/>\n<meta property=\"og:description\" content=\"Subtitle: per determinare le coordinate geografiche della nave con rette d&#039;altezzaAuthor: giorgio sorrentinoPublisher: stabilimento tipografico e. pietrocolaISBN: LDM1754411362\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T22:17:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/manuale-di-navigazione-giorgio-sorrentino-stabilimento-tipografico-e-pietrocola-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"715\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;60,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"Out of stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\\\/\",\"name\":\"manuale di navigazione - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/manuale-di-navigazione-giorgio-sorrentino-stabilimento-tipografico-e-pietrocola-2.jpg\",\"datePublished\":\"2025-08-05T16:29:24+00:00\",\"dateModified\":\"2026-07-10T22:17:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/manuale-di-navigazione-giorgio-sorrentino-stabilimento-tipografico-e-pietrocola-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/manuale-di-navigazione-giorgio-sorrentino-stabilimento-tipografico-e-pietrocola-2.jpg\",\"width\":500,\"height\":715},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"manuale di navigazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"60.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1754411362\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"manuale di navigazione - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/","og_locale":"en_US","og_type":"article","og_title":"manuale di navigazione","og_description":"Subtitle: per determinare le coordinate geografiche della nave con rette d'altezzaAuthor: giorgio sorrentinoPublisher: stabilimento tipografico e. pietrocolaISBN: LDM1754411362","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-07-10T22:17:04+00:00","og_image":[{"width":500,"height":715,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/manuale-di-navigazione-giorgio-sorrentino-stabilimento-tipografico-e-pietrocola-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;60,00","Availability":"Out of stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/","name":"manuale di navigazione - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/manuale-di-navigazione-giorgio-sorrentino-stabilimento-tipografico-e-pietrocola-2.jpg","datePublished":"2025-08-05T16:29:24+00:00","dateModified":"2026-07-10T22:17:04+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/manuale-di-navigazione-giorgio-sorrentino-stabilimento-tipografico-e-pietrocola-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/manuale-di-navigazione-giorgio-sorrentino-stabilimento-tipografico-e-pietrocola-2.jpg","width":500,"height":715},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/manuale-di-navigazione-giorgio-sorrentino-ldm1754411362\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"manuale di navigazione"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"60.00","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"LDM1754411362","product_condition":"new"},"df_price":60,"df_sale_price":"","df_regular_price":60,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/manuale-di-navigazione-giorgio-sorrentino-stabilimento-tipografico-e-pietrocola-2-210x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/153695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=153695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/158280"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=153695"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=153695"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=153695"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=153695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}