{"id":149506,"date":"2025-06-04T13:01:14","date_gmt":"2025-06-04T11:01:14","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/"},"modified":"2026-05-09T00:13:16","modified_gmt":"2026-05-08T22:13:16","slug":"sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/","title":{"rendered":"sirene, conchiglie e incantesimi &#8211; pennelli magici"},"content":{"rendered":"<p><strong>Coloratissime immagini<\/strong> con il libro dei pennelli magici. Dipingi solo con acqua, lascia asciugare, poi colora ancora.&nbsp;<\/p>\n<p>In questo libro troverai <strong>tanti disegni da colorare<\/strong>, <strong>fantastiche notizie <\/strong>e una gran quantit&agrave; di <strong>pagine da scarabocchiare<\/strong> per provare le tue nuove abilit&agrave; pittoriche!<\/p>\n<p>Et&agrave;: <strong>3+<\/strong><\/p>\n<p>Edizione: 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"autore\"><span>Author: <\/span>jeny copper &#8211; illustrazioni di rachael mclean<\/p>\n<p class=\"editore\"><span>Publisher: <\/span>ape junior (adriano salani editore)<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>9791256600717<\/p>\n","protected":false},"featured_media":149504,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2616],"product_tag":[],"class_list":{"0":"post-149506","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-activity-books","8":"first","9":"onbackorder","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>sirene, conchiglie e incantesimi - pennelli magici - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sirene, conchiglie e incantesimi - pennelli magici\" \/>\n<meta property=\"og:description\" content=\"Author: jeny copper - illustrazioni di rachael mcleanPublisher: ape junior (adriano salani editore)ISBN: 9791256600717\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sirene-pennelli-magici-ape-junior.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"530\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;9,90\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\\\/\",\"name\":\"sirene, conchiglie e incantesimi - pennelli magici - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sirene-pennelli-magici-ape-junior.jpg\",\"datePublished\":\"2025-06-04T11:01:14+00:00\",\"dateModified\":\"2026-05-08T22:13:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sirene-pennelli-magici-ape-junior.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/sirene-pennelli-magici-ape-junior.jpg\",\"width\":530,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"sirene, conchiglie e incantesimi &#8211; pennelli magici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"9.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"9791256600717\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"sirene, conchiglie e incantesimi - pennelli magici - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/","og_locale":"en_US","og_type":"article","og_title":"sirene, conchiglie e incantesimi - pennelli magici","og_description":"Author: jeny copper - illustrazioni di rachael mcleanPublisher: ape junior (adriano salani editore)ISBN: 9791256600717","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:13:16+00:00","og_image":[{"width":530,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sirene-pennelli-magici-ape-junior.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;9,90","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/","name":"sirene, conchiglie e incantesimi - pennelli magici - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sirene-pennelli-magici-ape-junior.jpg","datePublished":"2025-06-04T11:01:14+00:00","dateModified":"2026-05-08T22:13:16+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sirene-pennelli-magici-ape-junior.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sirene-pennelli-magici-ape-junior.jpg","width":530,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/sirene-conchiglie-e-incantesimi-pennelli-magici-jeny-copper-illustrazioni-di-rachael-mclean-9791256600717\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"sirene, conchiglie e incantesimi &#8211; pennelli magici"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"9.90","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"9791256600717","product_condition":"new"},"df_price":9.9,"df_sale_price":"","df_regular_price":9.9,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/sirene-pennelli-magici-ape-junior-227x300.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/149506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=149506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/149504"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=149506"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=149506"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=149506"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=149506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}