{"id":148992,"date":"2025-05-20T17:52:06","date_gmt":"2025-05-20T15:52:06","guid":{"rendered":"https:\/\/libreriadelmare.it\/negozio\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/"},"modified":"2026-05-09T00:13:48","modified_gmt":"2026-05-08T22:13:48","slug":"framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324","status":"publish","type":"product","link":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/","title":{"rendered":"framed print &#8220;drypoint &#8211; imprese pericolose (4\/4)&#8221;"},"content":{"rendered":"<p>The <strong>drypoint technique<\/strong> consists of hand engraving <strong>a zinc plate<\/strong> with a Haden type point of hardened steel. <strong>Small metal burr<\/strong> on the edges of the obtained grooves retain the ink. Immediately after, <strong>a sheet of Hahnemuhle cotton paper<\/strong> is placed on the hand-inked plate and run throuh an etching press: the pressure between the sheet and the plate allows the mold and the coloring of the drawing.<\/p>\n<p><strong>Limited edition: n. 4\/4 (2020).<\/strong><\/p>\n<p>White lacquered wooden frame with passepartout and glass.<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"sottotitolo\"><span>Subtitle: <\/span>43&#215;33 cm<\/p>\n<p class=\"autore\"><span>Author: <\/span>ab<\/p>\n<p class=\"editore\"><span>Manufacturer: <\/span>astuteart<\/p>\n<p class=\"isbn\"><span>ISBN: <\/span>LDM1747756324<\/p>\n","protected":false},"featured_media":156817,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[2435],"product_tag":[],"class_list":{"0":"post-148992","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cartography-lighthouses-and-landscapes","7":"product_shipping_class-packaging","9":"first","10":"onbackorder","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>framed print &quot;drypoint - imprese pericolose (4\/4)&quot; - Libreria del Mare<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"framed print &quot;drypoint - imprese pericolose (4\/4)&quot;\" \/>\n<meta property=\"og:description\" content=\"Subtitle: 43x33 cmAuthor: abManufacturer: astuteartISBN: LDM1747756324\" \/>\n<meta property=\"og:url\" content=\"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria del Mare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/libreriadelmare\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:13:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-puntasecca-imprese-pericolose-4-4-astute-art-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;280,00\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"On backorder\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\\\/\",\"name\":\"framed print \\\"drypoint - imprese pericolose (4\\\/4)\\\" - Libreria del Mare\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-puntasecca-imprese-pericolose-4-4-astute-art-2.jpg\",\"datePublished\":\"2025-05-20T15:52:06+00:00\",\"dateModified\":\"2026-05-08T22:13:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\\\/#primaryimage\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-puntasecca-imprese-pericolose-4-4-astute-art-2.jpg\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/quadro-puntasecca-imprese-pericolose-4-4-astute-art-2.jpg\",\"width\":900,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"framed print &#8220;drypoint &#8211; imprese pericolose (4\\\/4)&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"name\":\"Libreria del Mare - Milano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#organization\",\"name\":\"Libreria del Mare - Milano\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"contentUrl\":\"https:\\\/\\\/libreriadelmare.it\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/logo-blu.png\",\"width\":600,\"height\":162,\"caption\":\"Libreria del Mare - Milano\"},\"image\":{\"@id\":\"https:\\\/\\\/libreriadelmare.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/libreriadelmare\",\"https:\\\/\\\/www.instagram.com\\\/libreriadelmare\\\/\"],\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/libreriadelmare.it\\\/diritto-di-recesso\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"280.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"backorder\" \/>\n<meta property=\"product:availability\" content=\"available for order\" \/>\n<meta property=\"product:retailer_item_id\" content=\"LDM1747756324\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"framed print \"drypoint - imprese pericolose (4\/4)\" - Libreria del Mare","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/","og_locale":"en_US","og_type":"article","og_title":"framed print \"drypoint - imprese pericolose (4\/4)\"","og_description":"Subtitle: 43x33 cmAuthor: abManufacturer: astuteartISBN: LDM1747756324","og_url":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/","og_site_name":"Libreria del Mare","article_publisher":"https:\/\/www.facebook.com\/libreriadelmare","article_modified_time":"2026-05-08T22:13:48+00:00","og_image":[{"width":900,"height":700,"url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-puntasecca-imprese-pericolose-4-4-astute-art-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"&euro;280,00","Availability":"On backorder"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/","url":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/","name":"framed print \"drypoint - imprese pericolose (4\/4)\" - Libreria del Mare","isPartOf":{"@id":"https:\/\/libreriadelmare.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/#primaryimage"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/#primaryimage"},"thumbnailUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-puntasecca-imprese-pericolose-4-4-astute-art-2.jpg","datePublished":"2025-05-20T15:52:06+00:00","dateModified":"2026-05-08T22:13:48+00:00","breadcrumb":{"@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/#primaryimage","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-puntasecca-imprese-pericolose-4-4-astute-art-2.jpg","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-puntasecca-imprese-pericolose-4-4-astute-art-2.jpg","width":900,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/libreriadelmare.it\/en\/shop\/framed-print-drypoint-imprese-pericolose-4-4-ab-ldm1747756324\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/libreriadelmare.it\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/libreriadelmare.it\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"framed print &#8220;drypoint &#8211; imprese pericolose (4\/4)&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/libreriadelmare.it\/en\/#website","url":"https:\/\/libreriadelmare.it\/en\/","name":"Libreria del Mare - Milano","description":"","publisher":{"@id":"https:\/\/libreriadelmare.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/libreriadelmare.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/libreriadelmare.it\/en\/#organization","name":"Libreria del Mare - Milano","url":"https:\/\/libreriadelmare.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","contentUrl":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/2018\/07\/logo-blu.png","width":600,"height":162,"caption":"Libreria del Mare - Milano"},"image":{"@id":"https:\/\/libreriadelmare.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/libreriadelmare","https:\/\/www.instagram.com\/libreriadelmare\/"],"hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/libreriadelmare.it\/diritto-di-recesso\/"}}]},"product_price_amount":"280.00","product_price_currency":"EUR","og_availability":"backorder","product_availability":"available for order","product_retailer_item_id":"LDM1747756324","product_condition":"new"},"df_price":280,"df_sale_price":"","df_regular_price":280,"df_image_link":"https:\/\/libreriadelmare.it\/wp-content\/uploads\/quadro-puntasecca-imprese-pericolose-4-4-astute-art-2-300x233.jpg","_links":{"self":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product\/148992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/comments?post=148992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media\/156817"}],"wp:attachment":[{"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/media?parent=148992"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_brand?post=148992"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_cat?post=148992"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/libreriadelmare.it\/en\/wp-json\/wp\/v2\/product_tag?post=148992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}